{"id":10329,"date":"2024-11-01T14:49:33","date_gmt":"2024-11-01T13:49:33","guid":{"rendered":"https:\/\/jansa.serveistic.com\/enclosures\/"},"modified":"2026-05-04T14:03:32","modified_gmt":"2026-05-04T12:03:32","slug":"enclosures","status":"publish","type":"page","link":"https:\/\/jansametal.com\/en\/enclosures\/","title":{"rendered":"Enclosures"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-37fe9e23 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d36b578f\"><h1 class=\"uagb-heading-text\">Enclosures<\/h1><\/div>\n<\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-ad563c4a alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-3e42084d\">\n<h2 class=\"wp-block-heading has-text-align-left\">Metal structure enclosures and roofing designed to protect your building, optimize its performance and ensure long-term durability.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:-30px\">Imagine a <strong>building roof<\/strong> capable of withstanding any weather condition, maintaining safety without sacrificing modern design. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:-30px\">From <strong>industrial enclosures<\/strong> to roofing for industrial buildings, our solutions are built to last and deliver maximum performance. Forget about leaks, unnecessary maintenance and the premature deterioration of your building. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-67f856b6\">\n<div class=\"wp-block-uagb-image uagb-block-e916b720 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/01\/cerramiento_nave_industrial.png\" alt=\"\" class=\"uag-image-5691\" width=\"5100\" height=\"3300\" title=\"industrial_warehouse_enclosure\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-8c2619f3\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-1b5c9ed9 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/jansametal.com\/en\/parts-of-a-metal-structure\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">View structure parts<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-0836edbd alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-call-to-action uagb-block-cc2d3143 wp-block-button\"><div class=\"uagb-cta__wrap\"><h3 class=\"uagb-cta__title\">Contract the fabrication of your building<\/h3><p class=\"uagb-cta__desc\">With us, you have the opportunity to carry out a complete project with an architectural solution that enhances your building\u2019s performance and ensures real savings in energy costs.<\/p><\/div><div class=\"uagb-cta__buttons\"><a href=\"https:\/\/jansametal.com\/en\/what-is-your-project-like\/\" class=\"uagb-cta__button-link-wrapper wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\">more info<svg viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\"><strong>*Service available <mark style=\"background-color:var(--ast-global-color-0)\" class=\"has-inline-color has-ast-global-color-5-color\">exclusively <\/mark>with the full project contract.<\/strong><\/p>\n<\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-f528b674 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-5daedf69 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Our solutions<\/h2><\/div><p class=\"uagb-ifb-desc\">Each <strong>steel fa\u00e7ade<\/strong> is manufactured with advanced materials, ensuring high thermal and acoustic insulation capacity. The sandwich panel used in our enclosures may contain an insulating core of polyurethane foam or rock wool. <\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-bd486be1 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-05b13c07 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Jansline<\/h3><\/div><p class=\"uagb-ifb-desc\">Horizontal fa\u00e7ade system.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-ec897ce7 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong><strong><strong><strong>JansWall<\/strong><\/strong><\/strong><\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Fa\u00e7ades made with vertical sandwich panels.<\/p><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-0fdffcab uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong><strong><strong><strong>Insulation<\/strong><\/strong><\/strong><\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Sandwich panel with a thermal transmittance coefficient (K) ranging from 0.52 to 0.16 Kcal\/h\u00b7m\u00b2\u00b7\u00baC.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-b9416cf0 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong><strong><strong><strong>Jansconfort<\/strong><\/strong><\/strong><\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Duplex system specially designed for building applications, consisting of: <strong>inner layer of sheet metal\/drywall + rock wool insulation + polyurethane sandwich panel.<\/strong><\/p><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-2bed7e08 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong><strong><strong><strong>Jansroof<\/strong><\/strong><\/strong><\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Three-rib roof sandwich panel, either joint or overlapped, with insulation thickness ranging from 30 to 120 mm.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-29b0edf3 uagb-infobox__content-wrap  uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-tablet uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong><strong><strong><strong>Jansdeck<\/strong><\/strong><\/strong><\/strong><\/h3><\/div><p class=\"uagb-ifb-desc\">Flat roof with sandwich panel from 30 to 120 mm and waterproof coating<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-82860771 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-marketing-button uagb-marketing-btn__align-center uagb-marketing-btn__align-text-center uagb-marketing-btn__icon-after uagb-block-0a68c273 wp-block-button\"><a href=\"\/contacto\/\" class=\"uagb-marketing-btn__link wp-block-button__link\" target=\"\" rel=\"noopener noreferrer\"><span class=\"uagb-marketing-btn__title\">Request a quote<\/span><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M384 320c-17.67 0-32 14.33-32 32v96H64V160h96c17.67 0 32-14.32 32-32s-14.33-32-32-32L64 96c-35.35 0-64 28.65-64 64V448c0 35.34 28.65 64 64 64h288c35.35 0 64-28.66 64-64v-96C416 334.3 401.7 320 384 320zM488 0H352c-12.94 0-24.62 7.797-29.56 19.75c-4.969 11.97-2.219 25.72 6.938 34.88L370.8 96L169.4 297.4c-12.5 12.5-12.5 32.75 0 45.25C175.6 348.9 183.8 352 192 352s16.38-3.125 22.62-9.375L416 141.3l41.38 41.38c9.156 9.141 22.88 11.84 34.88 6.938C504.2 184.6 512 172.9 512 160V24C512 10.74 501.3 0 488 0z\"><\/path><\/svg><p class=\"uagb-marketing-btn__prefix\">AND GET YOUR STRUCTURE IN JUST A FEW WEEKS<\/p><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-933ce29f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-420957bb\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-973044c4\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fb345f9d\"><h2 class=\"uagb-heading-text\"><strong>What advantages do modular panel systems offer for roofs and fa\u00e7ades?<\/strong><\/h2><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:-10px\">The panel systems for roofs and fa\u00e7ades offered by Jansa Metal stand out for:<\/p>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-f755cec1\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-ed470cbd\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>Fast installation<\/strong><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-f1c057f4\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>Efficient thermal and acoustic insulation<\/strong><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-2ba4170d\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>Ability to adapt to different building configurations<\/strong><\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-aad0a1f2\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>Design flexibility<\/strong><\/span><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:-10px\"><strong>With over 35 years of experience, Jansa Metal guarantees solid and efficient results in every project.<\/strong><\/p>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-94d98ee3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-33018f89     \"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--carousel\">\n\t\t\t\t\t\t\t\t<div class=\"uagb-slick-carousel uagb-block-33018f89\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"5376\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/nave_industrial-1-1024x796.jpeg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/nave_industrial-1-1024x796.jpeg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/nave_industrial-1-300x233.jpeg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"4742\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/Navepreingeniada-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/Navepreingeniada-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/Navepreingeniada-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"5165\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/casas_preingeniadas-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/casas_preingeniadas-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/casas_preingeniadas-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"4658\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/20230416_115938-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/20230416_115938-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/20230416_115938-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"6599\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubierta_de_edificio-1024x766.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubierta_de_edificio-1024x766.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubierta_de_edificio-300x224.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"6595\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_para_edificios-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_para_edificios-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_para_edificios-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"6591\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_metalicos-1024x768.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_metalicos-1024x768.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_metalicos-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"6587\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_exteriores-1024x766.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_exteriores-1024x766.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cerramientos_exteriores-300x224.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"6603\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubiertas_edificios.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubiertas_edificios.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubiertas_edificios-300x225.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"6611\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/casas_estructura_metalica-1024x819.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/casas_estructura_metalica-1024x819.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/casas_estructura_metalica-300x240.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-wrapper\" data-spectra-gallery-image-id=\"6615\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubiertas_metalicas-1024x683.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubiertas_metalicas-1024x683.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel\" src=\"https:\/\/jansametal.com\/wp-content\/uploads\/2025\/03\/cubiertas_metalicas-300x200.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-33b2e460 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-dd5d62ed alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-3ac9af46\">\n<h2 class=\"wp-block-heading has-text-align-center\">FAQ&#8217;s<\/h2>\n\n\n\n<div class=\"wp-block-wpsp-faq wpsp-faq__outer-wrap wpsp-block-ed0cca32 wpsp-faq-icon-row wpsp-faq-layout-accordion wpsp-faq-expand-first-false wpsp-faq-inactive-other-true wpsp-faq-equal-height\" data-faqtoggle=\"true\" role=\"tablist\"><script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"FAQPage\",\"@id\":\"https:\/\/jansametal.com\/cerramientos-cubiertas\/\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"\u00bfQu\u00e9 tipos de panel s\u00e1ndwich existen para cubiertas y fachadas?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Existen diferentes tipos de panel s\u00e1ndwich seg\u00fan su aplicaci\u00f3n y nivel de aislamiento:&lt;br>  - &lt;strong>Panel s\u00e1ndwich para fachadas&lt;\/strong>: montados en horizontal (JansLine) o en vertical (JansWall).&lt;br>  - &lt;strong>Panel s\u00e1ndwich para cubiertas&lt;\/strong>: inclinadas (JansRoof) o planas (JansDeck).&lt;br>  - &lt;strong>Panel s\u00e1ndwich con alto aislamiento&lt;\/strong>: sistema JansConfort con doble capa y n\u00facleo de lana de roca o poliuretano.&lt;br>&lt;br>Cada sistema est\u00e1 dise\u00f1ado para ofrecer la mejor eficiencia energ\u00e9tica y adaptarse a las necesidades del proyecto.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfQu\u00e9 ventajas tiene el panel s\u00e1ndwich en cubiertas y fachadas?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"El uso de panel s\u00e1ndwich aporta m\u00faltiples beneficios:&lt;br>  - &lt;strong>Alta eficiencia&lt;\/strong> t\u00e9rmica y ac\u00fastica&lt;br>  - &lt;strong>R\u00e1pida instalaci\u00f3n&lt;\/strong> y m\u00ednimo mantenimiento&lt;br>  - Excelente &lt;strong>resistencia&lt;\/strong> a la intemperie&lt;br>  - &lt;strong>Reducci\u00f3n del consumo&lt;\/strong> energ\u00e9tico&lt;br>  - &lt;strong>Adaptabilidad&lt;\/strong> a distintos dise\u00f1os y necesidades constructivas&lt;br>&lt;br>Nuestros sistemas est\u00e1n pensados para ofrecer rendimiento, est\u00e9tica y durabilidad a largo plazo.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfQu\u00e9 aislamiento t\u00e9rmico ofrecen vuestros cerramientos?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Nuestros paneles s\u00e1ndwich pueden alcanzar coeficientes de transmisi\u00f3n t\u00e9rmica (&lt;strong>K&lt;\/strong>) desde &lt;strong>0.52 hasta 0.16 Kcal\/h\u00b7m\u00b2\u00b7\u00baC&lt;\/strong>, dependiendo del tipo de aislamiento (espuma de poliuretano o lana de roca) y del espesor del panel. Esto se traduce en un &lt;strong>ahorro energ\u00e9tico real&lt;\/strong> en climatizaci\u00f3n para tu edificio.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfEn qu\u00e9 tipos de edificios se pueden instalar estos sistemas?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Nuestros cerramientos est\u00e1n dise\u00f1ados para adaptarse a todo tipo de construcciones:&lt;br>  - &lt;strong>Naves industriales y log\u00edsticas&lt;\/strong>&lt;br>  - &lt;strong>Edificios de oficinas&lt;\/strong>&lt;br>  - &lt;strong>Centros comerciales&lt;\/strong>&lt;br>&lt;strong>Instalaciones deportivas&lt;\/strong>&lt;br>  - &lt;strong>Viviendas unifamiliares&lt;\/strong>&lt;br>&lt;br>Solo ofrecemos estos sistemas dentro de la &lt;strong>contrataci\u00f3n completa del proyecto&lt;\/strong>, asegurando as\u00ed una ejecuci\u00f3n perfecta y sin errores de integraci\u00f3n.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfCu\u00e1l es el mejor cerramiento para una nave industrial?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"El cerramiento m\u00e1s eficiente para una nave industrial es el &lt;strong>panel s\u00e1ndwich met\u00e1lico con n\u00facleo aislante&lt;\/strong>, ya sea de &lt;strong>poliuretano&lt;\/strong> o &lt;strong>lana de roca&lt;\/strong>. Este tipo de cerramiento ofrece:&lt;br>&lt;br>  - M\u00e1xima &lt;strong>resistencia&lt;\/strong> al fuego y al clima&lt;br>  - Excelente &lt;strong>aislamiento&lt;\/strong> t\u00e9rmico y ac\u00fastico &lt;br>  - &lt;strong>Reducci\u00f3n de costes&lt;\/strong> energ\u00e9ticos&lt;br>  - &lt;strong>Montaje r\u00e1pido&lt;\/strong> y sin apenas mantenimiento&lt;br>&lt;br>En Jansa Metal dise\u00f1amos soluciones personalizadas seg\u00fan el tipo de nave y el rendimiento requerido.\"}}]}<\/script><div class=\"wpsp-faq__wrap wpsp-buttons-layout-wrap\">\n<div class=\"wp-block-wpsp-faq-child wpsp-faq-child__outer-wrap wpsp-block-6b870f6f\"><div class=\"wpsp-faq-child__wrapper\"><div class=\"wpsp-faq-item\" role=\"tab\" tabindex=\"0\"><div class=\"wpsp-faq-questions-button wpsp-faq-questions\"><span class=\"wpsp-icon wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"wpsp-icon-active wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><h3 class=\"wpsp-question\">What types of sandwich panels are available for roofs and fa\u00e7ades?<\/h3><\/div><div class=\"wpsp-faq-content\"><span><p>There are different types of sandwich panels depending on their application and insulation level:<br\/>&#8211; <strong>Fa\u00e7ade sandwich panels<\/strong>: mounted horizontally (JansLine) or vertically (JansWall)<br\/>&#8211; <strong>Roof sandwich panels<\/strong>: for pitched roofs (JansRoof) or flat roofs (JansDeck)<br\/>&#8211; <strong>High-insulation sandwich panels<\/strong>: JansConfort system with double layer and rock wool or polyurethane core<br\/><br\/>Each system is designed to provide optimal energy efficiency and adapt to the needs of the project.<\/p><\/span><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-wpsp-faq-child wpsp-faq-child__outer-wrap wpsp-block-ae1c76a3\"><div class=\"wpsp-faq-child__wrapper\"><div class=\"wpsp-faq-item\" role=\"tab\" tabindex=\"0\"><div class=\"wpsp-faq-questions-button wpsp-faq-questions\"><span class=\"wpsp-icon wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"wpsp-icon-active wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><h3 class=\"wpsp-question\">What advantages do sandwich panels offer for roofs and fa\u00e7ades?<\/h3><\/div><div class=\"wpsp-faq-content\"><span><p>The use of sandwich panels offers multiple benefits:<br\/>&#8211; <strong>High thermal<\/strong> and acoustic efficiency<br\/>&#8211; <strong>Fast installation<\/strong> and minimal maintenance<br\/>&#8211; Excellent weather <strong>resistance<\/strong><br\/>&#8211; <strong>Reduced energy<\/strong> consumption<br\/>&#8211; <strong>Adaptability<\/strong> to different designs and construction requirements<br\/><br\/>Our systems are designed to deliver performance, aesthetics, and long-term durability.<\/p><\/span><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-wpsp-faq-child wpsp-faq-child__outer-wrap wpsp-block-adf56f38\"><div class=\"wpsp-faq-child__wrapper\"><div class=\"wpsp-faq-item\" role=\"tab\" tabindex=\"0\"><div class=\"wpsp-faq-questions-button wpsp-faq-questions\"><span class=\"wpsp-icon wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"wpsp-icon-active wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><h3 class=\"wpsp-question\">What level of thermal insulation do your enclosures provide?<\/h3><\/div><div class=\"wpsp-faq-content\"><span><p>Our sandwich panels can achieve thermal transmittance coefficients (<strong>K<\/strong>) ranging from <strong>0.52 to 0.16 Kcal\/h\u00b7m\u00b2\u00b7\u00baC<\/strong>, depending on the type of insulation (polyurethane foam or rock wool) and panel thickness.<br\/>This translates into<strong> real energy savings<\/strong> in climate control for your building. <\/p><\/span><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-wpsp-faq-child wpsp-faq-child__outer-wrap wpsp-block-f3e35e7a\"><div class=\"wpsp-faq-child__wrapper\"><div class=\"wpsp-faq-item\" role=\"tab\" tabindex=\"0\"><div class=\"wpsp-faq-questions-button wpsp-faq-questions\"><span class=\"wpsp-icon wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"wpsp-icon-active wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><h3 class=\"wpsp-question\">In what types of buildings can these systems be installed?<\/h3><\/div><div class=\"wpsp-faq-content\"><span><p>Our enclosures are designed to adapt to all types of constructions:<br\/>&#8211; <strong>Industrial and logistics warehouses<\/strong><br\/>&#8211; <strong>Office buildings<\/strong><br\/>&#8211; <strong>Shopping centers<\/strong><br\/><strong>Sports facilities<\/strong><br\/>&#8211; <strong>Single-family homes<\/strong><br\/><br\/>These systems are only offered as part of a <strong>full project contract<\/strong>, thus ensuring flawless execution and integration.<\/p><\/span><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-wpsp-faq-child wpsp-faq-child__outer-wrap wpsp-block-b97b037f\"><div class=\"wpsp-faq-child__wrapper\"><div class=\"wpsp-faq-item\" role=\"tab\" tabindex=\"0\"><div class=\"wpsp-faq-questions-button wpsp-faq-questions\"><span class=\"wpsp-icon wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><span class=\"wpsp-icon-active wpsp-faq-icon-wrap\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span><h3 class=\"wpsp-question\">What is the best enclosure for an industrial building?<\/h3><\/div><div class=\"wpsp-faq-content\"><span><p>The most efficient enclosure for an industrial warehouse is the metal sandwich<strong> panel with an insulating core<\/strong>, either <strong>polyurethane<\/strong> or <strong>rock wool<\/strong>. This type of enclosure offers: <br\/><br\/> &#8211; Maximum fire and weather<strong> resistance<\/strong><br\/>&#8211; Excellent thermal and acoustic <strong>insulation<\/strong><br\/>&#8211; <strong>Reduced energy costs<\/strong><br\/>&#8211; <strong>Fast installation<\/strong> with minimal maintenance<br\/><br\/>At Jansa Metal, we design custom solutions based on the type of warehouse and the required performance.<\/p><\/span><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-64d3b7bb alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-01a5eb8e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-3c79a888 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a6b1f9db\">\n<div class=\"wp-block-uagb-container uagb-block-3b8ab2e1\">\n<h2 class=\"wp-block-heading\"><strong>Ready for the First Step?<\/strong> Contact us!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Every great project starts with a conversation. <strong>Contact us<\/strong>, and find out how we can bring your idea to reality, with metal structures that are as solid as your expectations.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b0aef8d0\">\n<div class=\"wp-block-uagb-container uagb-block-c8e181d6 alignwide uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-2095f831\">\t\t\t\t<div class = \"wp-block-uagb-cf7-styler uagb-cf7-styler__outer-wrap uagb-block-0bbd5a13   \">\n\t\t\t\t\t<div class = \"uagb-cf7-styler__align-left uagb-cf7-styler__field-style-underline uagb-cf7-styler__btn-align-center uagb-cf7-styler__btn-align-tablet- uagb-cf7-styler__btn-align-mobile- uagb-cf7-styler__highlight-style-default uagb-cf7-styler__check-style-enabled\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13376-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"13376\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/10329#wpcf7-f13376-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"13376\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13376-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Name*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Last Name*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"apellido\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"apellido\" \/><\/span> <\/label>\n<\/p>\n<p><label> Email*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Phone<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span><\/label>\n<\/p>\n<p><label> Affair*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Consultation<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"term_and_conditions\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"term_and_conditions\" value=\"1\" class=\"required\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I have read and agree to the <a href=\"..\/es\/aviso-legal\/\">legal notice and Terms of Use<\/a>, and the <a href=\"..\/es\/politica-de-privacidad\/\">Privacy<\/a> and <a href=\"..\/es\/politica-de-cookies\/\">Cookie Policies.<\/a><\/span><\/label><\/span><\/span><\/span>\n<\/p>\n\n<!--[cf7sr-simple-recaptcha] -->\n\n<!-- [anr_nocaptcha g-recaptcha-response] -->\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enclosures Metal structure enclosures and roofing designed to protect your building, optimize its performance and ensure long-term durability. Imagine a building roof capable of withstanding any weather condition, maintaining safety without sacrificing modern design. From industrial enclosures to roofing for industrial buildings, our solutions are built to last and deliver maximum performance. Forget about leaks, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-10329","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"adv-header-id-meta":[""],"stick-header-meta":[""],"theme-transparent-header-meta":[""],"ast-site-content-layout":["default"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_last_translation_edit_mode":["translation-editor"],"_wp_page_template":[""],"rank_math_og_content_image":["a:2:{s:5:\"check\";s:32:\"ea3b02e714902e8f1360f86845088bac\";s:6:\"images\";a:1:{i:0;i:5691;}}"],"rank_math_internal_links_processed":["1"],"_wpml_word_count":["753"],"_edit_lock":["1771239392:6"],"rank_math_seo_score":["65"],"_uag_custom_page_level_css":[""],"ast-disable-related-posts":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_edit_last":["6"],"_wpml_media_has_media":["1"],"rank_math_analytic_object_id":["106"],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"footer-sml-layout":[""],"header-main-stick-meta":[""],"header-above-stick-meta":[""],"header-below-stick-meta":[""],"site-post-title":["disabled"],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-featured-img":[""],"ast-breadcrumbs-content":[""],"ast-banner-title-visibility":[""],"ast-global-header-display":[""],"site-content-style":["default"],"site-sidebar-style":["default"],"rank_math_title":["Metal structure enclosures and roofing | Jansa Metal"],"rank_math_description":["We carry out metal structure enclosures and roofing exclusively in comprehensive projects where we are responsible for the entire structure of the building.\n"],"rank_math_focus_keyword":["metal structure enclosures and roofing"],"_uag_css_file_name":["uag-css-10329.css"],"_uag_js_file_name":["uag-js-10329.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:254244:\"\ufeff.wp-block-uagb-cf7-styler input[type=text],.wp-block-uagb-cf7-styler input[type=password],.wp-block-uagb-cf7-styler input[type=date],.wp-block-uagb-cf7-styler input[type=datetime],.wp-block-uagb-cf7-styler input[type=datetime-local],.wp-block-uagb-cf7-styler input[type=email],.wp-block-uagb-cf7-styler input[type=month],.wp-block-uagb-cf7-styler input[type=number],.wp-block-uagb-cf7-styler input[type=search],.wp-block-uagb-cf7-styler input[type=tel],.wp-block-uagb-cf7-styler input[type=time],.wp-block-uagb-cf7-styler input[type=url],.wp-block-uagb-cf7-styler input[type=week]{min-height:30px;line-height:30px}.wp-block-uagb-cf7-styler textarea{resize:vertical}.wp-block-uagb-cf7-styler .wpcf7 *,.wp-block-uagb-cf7-styler .wpcf7 ::after,.wp-block-uagb-cf7-styler .wpcf7 ::before{-webkit-box-sizing:border-box;box-sizing:border-box}.wp-block-uagb-cf7-styler span.wpcf7-list-item-label::before,.wp-block-uagb-cf7-styler span.wpcf7-list-item-label::after{content:\" \"}.wp-block-uagb-cf7-styler .wpcf7-acceptance input[type=checkbox]+span::before,.wp-block-uagb-cf7-styler .wpcf7-checkbox input[type=checkbox]+span::before,.wp-block-uagb-cf7-styler .wpcf7-radio input[type=radio]+span::before{display:inline-block;vertical-align:middle;width:15px;height:15px;margin-right:10px;border-color:#eaeaea;border-style:solid;border-width:1px 1px 1px 1px;text-align:center;content:\"\"}.wp-block-uagb-cf7-styler span.wpcf7-list-item{display:inline-block;margin:0 1em 0 0}.wp-block-uagb-cf7-styler .wpcf7-acceptance input[type=checkbox]:checked+span::before,.wp-block-uagb-cf7-styler .wpcf7-checkbox input[type=checkbox]:checked+span::before{line-height:1.2;content:\"\u2714\"}.wp-block-uagb-cf7-styler .wpcf7-acceptance input[type=checkbox]+span::before,.wp-block-uagb-cf7-styler .wpcf7-acceptance input[type=checkbox]:checked+span::before,.wp-block-uagb-cf7-styler .wpcf7-checkbox input[type=checkbox]+span::before,.wp-block-uagb-cf7-styler .wpcf7-checkbox input[type=checkbox]:checked+span::before,.wp-block-uagb-cf7-styler .wpcf7-radio input[type=radio]+span::before{-webkit-box-sizing:content-box;-moz-box-sizing:content-box;box-sizing:content-box}.wp-block-uagb-cf7-styler input[type=checkbox]:checked+span::before{font-size:-webkit-calc(12px \/ 1.2);font-size:10px}.wp-block-uagb-cf7-styler .wpcf7-radio input[type=radio]+span::before{-webkit-border-radius:100%;border-radius:100%}.wp-block-uagb-cf7-styler .uagb-cf7-styler__field-style-box .wpcf7-radio input[type=radio]:checked+span::before,.wp-block-uagb-cf7-styler .uagb-cf7-styler__field-style-underline .wpcf7-radio input[type=radio]:checked+span::before{box-shadow:inset 0 0 0 4px #fafafa;background-color:#545454}.wp-block-uagb-cf7-styler .uagb-cf7-styler__btn-align-justify input.wpcf7-form-control.wpcf7-submit,.wp-block-uagb-cf7-styler .uagb-cf7-styler__btn-align-left input.wpcf7-form-control.wpcf7-submit,.wp-block-uagb-cf7-styler .uagb-cf7-styler__btn-align-right input.wpcf7-form-control.wpcf7-submit,.wp-block-uagb-cf7-styler .uagb-cf7-styler__btn-align-center input.wpcf7-form-control.wpcf7-submit{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;width:auto;padding:10px 25px;background:rgba(0,0,0,0);border-color:#333;border-width:1px;line-height:16px;-js-display:flex}.wp-block-uagb-cf7-styler .wpcf7 input[type=checkbox],.wp-block-uagb-cf7-styler .wpcf7 input[type=radio]{display:none}.wp-block-uagb-cf7-styler .wpcf7 select{height:auto;padding:10px;-webkit-appearance:menulist-button;-moz-appearance:menulist-button}.wp-block-uagb-cf7-styler select.wpcf7-form-control.wpcf7-select[multiple=multiple]{padding:0}.wp-block-uagb-cf7-styler .wpcf7 select option{padding:10px}.wp-block-uagb-cf7-styler .uagb-cf7-styler__highlight-style-bottom_right span.wpcf7-not-valid-tip{display:block;padding:.1em .5em;margin-top:5px;border-radius:2px;font-size:.9em;-webkit-border-radius:2px;width:fit-content;margin-left:auto;margin-right:0}.wp-block-uagb-cf7-styler .wpcf7 input[type=number]{height:auto}.wp-block-uagb-cf7-styler .wpcf7 input.wpcf7-date{-webkit-appearance:none}.wp-block-uagb-cf7-styler .wpcf7-spinner{margin-top:25px}@media(min-width: 769px){.wp-block-uagb-cf7-styler .uagb-cf7_styler-col>p{-js-display:flex;display:-webkit-box;display:-webkit-flex;display:-moz-box;display:-ms-flexbox;display:flex;flex-wrap:wrap;width:100%}.wp-block-uagb-cf7-styler .uagb-cf7_styler-col label,.wp-block-uagb-cf7-styler .uagb-cf7_styler-col>p>span{-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1;flex:1;flex-grow:1}.wp-block-uagb-cf7-styler .uagb-cf7_styler-col br{display:none}.wp-block-uagb-cf7-styler .uagb-cf7_styler-col>p>span.uagb-cf7_styler-col-1{padding-right:15px;padding-left:0}.wp-block-uagb-cf7-styler .uagb-cf7_styler-col>p>span.uagb-cf7_styler-col-3{padding-right:0;padding-left:15px}.wp-block-uagb-cf7-styler .wpcf7 .uagb-cf7_styler-col span.wpcf7-form-control-wrap{height:100%}.wp-block-uagb-cf7-styler .wpcf7 .uagb-cf7_styler-col select{height:100%}}@media(min-width: 780px){.uagb-cf7-styler__btn-align-right input.wpcf7-form-control.wpcf7-submit{margin-right:0;margin-left:auto}.uagb-cf7-styler__btn-align-left input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:0}.uagb-cf7-styler__btn-align-center input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:auto}.uagb-cf7-styler__btn-align-justify input.wpcf7-form-control.wpcf7-submit{-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center;justify-content:center;width:100% !important}}@media(max-width: 780px){.uagb-cf7-styler__btn-align-tablet-right input.wpcf7-form-control.wpcf7-submit{margin-right:0;margin-left:auto}.uagb-cf7-styler__btn-align-tablet-left input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:0}.uagb-cf7-styler__btn-align-tablet-center input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:auto}}@media(min-width: 641px)and (max-width: 780px){.uagb-cf7-styler__btn-align-tablet-justify input.wpcf7-form-control.wpcf7-submit{-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center;justify-content:center;width:100% !important}}@media(max-width: 641px){.uagb-cf7-styler__btn-align-mobile-right input.wpcf7-form-control.wpcf7-submit{margin-right:0;margin-left:auto}.uagb-cf7-styler__btn-align-mobile-left input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:0}.uagb-cf7-styler__btn-align-mobile-center input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:auto}.uagb-cf7-styler__btn-align-mobile-justify input.wpcf7-form-control.wpcf7-submit{-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center;justify-content:center;width:100% !important}}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c8e181d6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-c8e181d6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2095f831{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2095f831 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2095f831{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-form{text-align: left;}.uagb-block-0bbd5a13 .wpcf7 form.wpcf7-form:not(input){color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 input:not([type=submit]){background-color: #283942;color: var(--ast-global-color-5);padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;text-align: left;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 select{background-color: #283942;color: var(--ast-global-color-5);text-align: left;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 select.wpcf7-form-control.wpcf7-select:not([multiple=\"multiple\"]){padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0bbd5a13 .wpcf7 select.wpcf7-select[multiple=\"multiple\"] option{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0bbd5a13 .wpcf7 textarea{background-color: #283942;color: var(--ast-global-color-5);padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;text-align: left;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 textarea::placeholder{color: var(--ast-global-color-5);text-align: left;}.uagb-block-0bbd5a13 .wpcf7 input::placeholder{color: var(--ast-global-color-5);text-align: left;}.uagb-block-0bbd5a13 .wpcf7 form input:not([type=submit]):focus{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 form select:focus{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 textarea:focus{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit{color: var(--ast-global-color-5);background-color: var(--ast-global-color-0);padding-left: 25px;padding-right: 25px;padding-top: 10px;padding-bottom: 10px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit:hover{border-color: #333;}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit:focus{border-color: #333;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{background-color: #283942;color: var(--ast-global-color-5);font-size: calc( 10px \/ 1.2 );border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{background-color: #283942;color: var(--ast-global-color-5);height: 10px;width: 10px;font-size: calc( 10px \/ 1.2 );border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{background-color: #283942;color: var(--ast-global-color-5);font-size: calc( 10px \/ 1.2 );border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{background-color: #283942;color: var(--ast-global-color-5);height: 10px;width: 10px;font-size: calc( 10px \/ 1.2 );border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-radio input[type=\"radio\"] + span:before{background-color: #283942;color: var(--ast-global-color-5);height: 10px;width: 10px;border-style: solid;border-color: var(--ast-global-color-0);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-radio input[type=\"radio\"]:checked + span:before{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input:not([type=submit]){border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;border-bottom-width: 1px;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline textarea{border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;border-bottom-width: 1px;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline select{border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;border-bottom-width: 1px;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-checkbox input[type=\"checkbox\"] + span:before{border-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input[type=\"radio\"] + span:before{border-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-acceptance input[type=\"checkbox\"] + span:before{border-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{font-size: calc( 10px \/ 1.2 );border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{font-size: calc( 10px \/ 1.2 );border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7-radio input[type=\"radio\"]:checked + span:before{background-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{background-color: var(--ast-global-color-5);color: var(--ast-global-color-0);font-size: calc( px \/ 1.2 );border-color: #abb8c3;}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{background-color: var(--ast-global-color-5);color: var(--ast-global-color-0);font-size: calc( px \/ 1.2 );border-color: #abb8c3;}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 input[type=\"radio\"] + span:before{background-color: var(--ast-global-color-5);color: var(--ast-global-color-0);font-size: calc( px \/ 1.2 );border-color: #abb8c3;}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7-radio input[type=\"radio\"]:checked + span:before{background-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 span.wpcf7-not-valid-tip{color: #ff0000;}.uagb-block-0bbd5a13 .uagb-cf7-styler__highlight-border input.wpcf7-form-control.wpcf7-not-valid{border-color: #ff0000;}.uagb-block-0bbd5a13 .uagb-cf7-styler__highlight-border .wpcf7-form-control.wpcf7-not-valid .wpcf7-list-item-label:before{border-color: #ff0000!important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c8e181d6{width: 100%;}.wp-block-uagb-container.uagb-block-c8e181d6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2095f831{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2095f831 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2095f831{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-0bbd5a13 .wpcf7 input:not([type=submit]){border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 select{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 textarea{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 input[type=\"radio\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .wpcf7 form.wpcf7-form:not(input){color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit{border-style: solid;border-color: #333;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input:not([type=submit]){border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline select{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-checkbox input[type='checkbox'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input[type='radio'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-acceptance input[type='checkbox'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline textarea{border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c8e181d6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-c8e181d6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2095f831{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2095f831 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2095f831{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-0bbd5a13 .wpcf7 input:not([type=submit]){border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 select{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 textarea{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 input[type=\"radio\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit{border-style: solid;border-color: #333;}.uagb-block-0bbd5a13 .wpcf7 form.wpcf7-form:not(input){color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input:not([type=submit]){border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline select{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-checkbox input[type='checkbox'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input[type='radio'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-acceptance input[type='checkbox'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline textarea{border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.uagb-cta__outer-wrap .uagb-cta__content,.uagb-cta__outer-wrap a.uagb-cta__block-link span,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__button-wrapper,.uagb-cta__outer-wrap .uagb-cta-typeof-button,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__outer-wrap .uagb-cta-with-svg{display:inline-block}.uagb-cta__outer-wrap{display:flex;justify-content:space-between}.wp-block-uagb-call-to-action .uagb-cta__buttons{display:inline-flex}.wp-block-uagb-call-to-action .wp-block-button__link,.wp-block-uagb-call-to-action .ast-outline-button{fill:currentColor;justify-content:center}.uagb-cta__button-link-wrapper,.uagb-cta-second__button{display:inline-flex;align-items:center;word-break:keep-all;width:100%}.uagb-cta__title{padding:0;margin:0;display:block}.uagb-cta__content-right .uagb-cta__button-wrapper{float:right}.uagb-cta__link-wrapper.uagb-cta__block-link-style:empty{display:none}a.uagb-cta__block-link,.entry .entry-content a.uagb-cta__block-link,a.uagb-cta__block-link-wrap,.entry .entry-content a.uagb-cta__block-link-wrap{text-decoration:none}a.uagb-cta__block-link:hover,.entry .entry-content a.uagb-cta__block-link:hover,a.uagb-cta__block-link-wrap:hover,.entry .entry-content a.uagb-cta__block-link-wrap:hover .entry .entry-content a.uagb-cta__block-link:hover{color:inherit}.uagb-cta__content-right{text-align:right;justify-content:flex-end}.uagb-cta__left-right-wrap{width:100%;word-break:break-word}.uagb-cta__icon-position-below-title .uagb-cta__left-right-wrap{display:block;min-width:100%;width:100%}.uagb-cta__icon-position-left .uagb-cta__left-right-wrap,.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{display:flex}.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{justify-content:flex-end}.uagb-cta__block-link-icon-after{margin-left:5px;margin-right:0}.uagb-cta__block-link-icon-before{margin-left:0;margin-right:5px}.uagb-cta__block-link-icon,.uagb-cta__block svg{transition:all 200ms linear}.uagb-cta__block{position:relative}.uagb-cta-typeof-button{line-height:1;text-align:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__content-right.uagb-cta__button-valign-middle .uagb-cta__left-right-wrap{display:flex;align-items:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link{justify-content:center}.uagb-cta__link-wrapper a{box-shadow:none;text-decoration:none}.uagb-cta__block,.uagb-cta__content,.uagb-cta__left-right-wrap{z-index:1}.uagb-cta__block-link{cursor:pointer}.uagb-cta__content-right .uagb-cta__block-link{float:right;padding:10px 14px}a.uagb-cta__block-link-wrap{color:inherit}.uagb-cta__content p:empty{display:none}.uagb-cta__button-type-none .uagb-cta__content{width:100%}.uagb-cta-with-svg{height:14px;width:14px;line-height:14px;vertical-align:middle}.uagb-cta__block svg{display:block;height:inherit;width:inherit}.uagb-cta__button-link-wrapper svg{width:20px;height:20px}.uagb-cta__align-button-after{margin-left:5px}.uagb-cta__align-button-before{margin-right:5px}.uagb-cta__block-link i{font-style:normal}a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.wp-block-uagb-call-to-action{position:relative}.wp-block-uagb-call-to-action a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}@media only screen and (max-width: 976px){.uagb-cta__content-stacked-tablet,.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}@media screen and (max-width: 767px){.uagb-cta__content-stacked-mobile,.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}.uagb-cta__desc p:last-child{margin-bottom:0}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-marketing-button{display:-webkit-box;display:-ms-flexbox;display:flex}.wp-block-uagb-marketing-button p:empty{display:none}.wp-block-uagb-marketing-button .uagb-marketing-btn__title,.wp-block-uagb-marketing-button p.uagb-marketing-btn__prefix{margin-bottom:0}.wp-block-uagb-marketing-button .uagb-marketing-btn__link{z-index:1;display:inline-block;position:relative;-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.wp-block-uagb-marketing-button .uagb-marketing-btn__link.wp-block-button__link{width:auto}.wp-block-uagb-marketing-button svg{fill:currentColor;width:20px;height:20px;z-index:1;vertical-align:middle}.wp-block-uagb-marketing-button .uagb-marketing-btn__title,.wp-block-uagb-marketing-button svg{display:inline;vertical-align:middle}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-center,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-center .uagb-marketing-btn__title-wrap,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-center .uagb-marketing-btn__link{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;text-align:center}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-left,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-left .uagb-marketing-btn__title-wrap,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-left .uagb-marketing-btn__link{-webkit-box-pack:start;-ms-flex-pack:start;justify-content:flex-start;text-align:left}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-right,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-right .uagb-marketing-btn__title-wrap,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-right .uagb-marketing-btn__link{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end;text-align:right}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-full .uagb-marketing-btn__link{width:100%}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-center .uagb-marketing-btn__prefix{text-align:center}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-left .uagb-marketing-btn__prefix{text-align:left}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-right .uagb-marketing-btn__prefix{text-align:right}.wp-block-uagb-marketing-button.uagb-marketing-btn__icon-after svg{order:2}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-full .uagb-marketing-btn__wrap{width:100%}.wp-block-uagb-marketing-button.uagb-marketing-btn__align-center .uagb-marketing-btn__wrap,.wp-block-uagb-marketing-button.uagb-marketing-btn__align-text-center .uagb-marketing-btn__title-wrap{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.wp-block-uagb-marketing-button .uagb-marketing-btn__title-wrap{display:-webkit-box;display:-ms-flexbox;display:flex;-webkit-box-align:self-end;-ms-flex-align:self-end;align-items:self-end}.wp-block-uagb-marketing-button.uagb-marketing-btn__icon-after .uagb-marketing-btn__icon-wrap{order:2}.entry-content .wp-block-uagb-marketing-button .uagb-marketing-btn__link{text-decoration:none;display:inline-block}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}\ufeff.wp-block-uagb-image-gallery{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;-webkit-justify-content:center;justify-content:center;flex-direction:column}.spectra-image-gallery *{box-sizing:border-box}.spectra-image-gallery__layout--grid{display:-moz-grid;display:-ms-grid;display:grid;grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--grid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--isogrid-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--isogrid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--masonry-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--carousel{width:100%}.spectra-image-gallery__layout--carousel .slick-initialized{visibility:visible}.spectra-image-gallery__layout--carousel .slick-track{display:flex;align-items:center}.spectra-image-gallery__layout--carousel .slick-slide .spectra-image-gallery__media-wrapper{display:block !important}.spectra-image-gallery__layout--carousel .slick-dots{padding:0;position:relative !important}.spectra-image-gallery__layout--carousel .slick-dots li button{padding:0}.spectra-image-gallery__layout--carousel .uagb-slick-carousel{padding:0}.spectra-image-gallery__layout--tiled{position:relative;display:grid;grid-auto-flow:dense;min-height:0;min-width:0}.spectra-image-gallery__layout--tiled-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__media{position:relative;overflow:hidden;-webkit-transition:box-shadow .25s;-moz-transition:box-shadow .25s;-o-transition:box-shadow .25s;transition:box-shadow .25s}.spectra-image-gallery__media--flagged{cursor:not-allowed}.spectra-image-gallery__media--clickable{cursor:pointer}.spectra-image-gallery__media--grid{aspect-ratio:1}.spectra-image-gallery__media--masonry{width:100%}.spectra-image-gallery__media--carousel{width:100%}.spectra-image-gallery__media--tiled{aspect-ratio:1;display:flex;align-items:center;justify-content:center}.spectra-image-gallery__media--tiled-wide,.spectra-image-gallery__media--tiled-tall{aspect-ratio:unset;width:100%;height:100%}.spectra-image-gallery__media--tiled picture{width:100%;height:100%}.spectra-image-gallery__media-sizer{aspect-ratio:1}.spectra-image-gallery__media-wrapper{position:relative}.spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__control-focus{opacity:.25}.spectra-image-gallery__media-thumbnail{vertical-align:middle;-webkit-transition:filter .5s,transform .5s;-moz-transition:filter .5s,transform .5s;-o-transition:filter .5s,transform .5s;transition:filter .5s,transform .5s}.spectra-image-gallery__media-thumbnail--grid{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail--masonry{width:100%}.spectra-image-gallery__media-thumbnail--carousel{width:100%}.spectra-image-gallery__media-thumbnail--tiled{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail-blurrer{position:absolute;top:0;left:0;width:100% !important;height:100% !important;-webkit-transition:box-shadow .25s,-webkit-backdrop-filter .5s;-moz-transition:box-shadow .25s,backdrop-filter .5s;-o-transition:box-shadow .25s,backdrop-filter .5s;transition:box-shadow .25s,backdrop-filter .5s}.spectra-image-gallery__media-thumbnail-caption{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__media-thumbnail-caption--overlay{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;height:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption--bar-inside{width:100%;overflow:hidden;padding:1em;max-height:90%}.spectra-image-gallery__media-thumbnail-caption--bar-outside{width:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption-wrapper{-webkit-transition:background-color .25s;-moz-transition:background-color .25s;-o-transition:background-color .25s;transition:background-color .25s}.spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{position:absolute;top:0;left:0;width:100%;height:100%}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{position:absolute;top:0;left:0;width:100%;height:100%;display:flex;overflow:hidden}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-outside{position:relative;width:100%;overflow:hidden}.spectra-image-gallery__control-wrapper{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;justify-content:center}.spectra-image-gallery__control-arrows{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;background-color:rgba(0,0,0,0);padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-arrows:disabled{opacity:.25;cursor:initial}.spectra-image-gallery__control-arrows:focus{background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-arrows--grid{border:none}.spectra-image-gallery__control-arrows svg{-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;padding:0 !important;margin:0 !important}.spectra-image-gallery__control-dots li{position:relative;display:inline-block;width:20px;height:20px;margin:0;padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-dots li button{font-size:0;line-height:0;display:block;box-sizing:border-box;width:20px;height:20px;padding:5px;cursor:pointer;color:rgba(0,0,0,0);border:0;outline:none;background:rgba(0,0,0,0);-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li button::before{font-family:none;font-size:30px;line-height:20px;position:absolute;top:0;left:0;width:20px;height:20px;content:\"\u2022\";text-align:center;opacity:.25;-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li.spectra-image-gallery__control-dot--active button::before{opacity:.75}.spectra-image-gallery__control-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.spectra-image-gallery__control-loader div{border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.spectra-image-gallery__control-button{cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-button.disabled{opacity:.25;pointer-events:none}.spectra-image-gallery__control-focus{cursor:pointer;position:absolute;box-sizing:content-box !important;top:0;right:0;width:1.5em;height:1.5em;padding:.5em;background-color:rgba(0,0,0,0);border:none;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-focus:hover{opacity:1 !important}.spectra-image-gallery__control-focus svg{fill:#fff;filter:drop-shadow(1px 1px 1px rgba(0, 0, 0, 0.5))}.spectra-image-gallery__control-lightbox{position:fixed;top:0;left:0;width:100vw !important;max-width:100vw !important;height:100vh !important;max-height:100vh !important;display:flex;flex-direction:column;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;z-index:999999999 !important;outline:none;margin-block-start:0;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--main{width:100%;flex:1}.spectra-image-gallery__control-lightbox--main .swiper-slide{height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center}.spectra-image-gallery__control-lightbox--main .swiper-slide img{display:block;max-height:70%;max-width:80%}.spectra-image-gallery__control-lightbox--caption{position:absolute;bottom:0;left:0;width:100%;display:flex;align-items:center;justify-content:center;text-align:center}.spectra-image-gallery__control-lightbox--editor-link{-webkit-transition-property:color;-moz-transition-property:color;-o-transition-property:color;transition-property:color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails{width:75%}.spectra-image-gallery__control-lightbox--thumbnails-wrapper{width:100%}.spectra-image-gallery__control-lightbox--thumbnails .swiper-wrapper{height:150px}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide{cursor:pointer;height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center;opacity:.5;transform:scale(75%);-webkit-transition-property:opacity,transform;-moz-transition-property:opacity,transform;-o-transition-property:opacity,transform;transition-property:opacity,transform;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide-active{opacity:1;transform:scale(100%)}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide img{border-radius:3px}.spectra-image-gallery__control-lightbox--count{position:absolute;z-index:999}.spectra-image-gallery__control-lightbox--close{position:absolute;cursor:pointer;padding:0;background-color:rgba(0,0,0,0);border:none;outline:0;line-height:0;z-index:999;transition:transform 500ms}.spectra-image-gallery__control-lightbox--close:hover,.spectra-image-gallery__control-lightbox--close:focus,.spectra-image-gallery__control-lightbox--close:focus-visible{background-color:rgba(0,0,0,0);transform:scale(1.25)}.spectra-image-gallery__iso-ref-wrapper{-ms-overflow-style:none;scrollbar-width:none}.spectra-image-gallery__iso-ref-wrapper::-webkit-scrollbar{display:none}@media(max-width: 976px){.spectra-image-gallery__layout--grid-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}@media(max-width: 767px){.spectra-image-gallery__layout--grid-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}.entry-content .wp-block-uagb-image-gallery .uagb-image-gallery__link{text-decoration:none}body .wp-block-post-content>.wp-block-uagb-image-gallery+.spectra-image-gallery__control-lightbox{margin-block-start:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__video-wrap video{opacity: 0.15;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-37fe9e23{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-37fe9e23{box-shadow: 0px 0px   #00000070 ;padding-top: 250px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/nave_industrial.jpeg);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-37fe9e23::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-1);opacity: 0.85;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading {text-align: center;margin-top: -80px;margin-right: 0px;margin-bottom: 20px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f .uagb-heading-text{font-size: 50px;}.wp-block-uagb-container.uagb-block-ad563c4a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ad563c4a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ad563c4a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ad563c4a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ad563c4a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad563c4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad563c4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ad563c4a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3e42084d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3e42084d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3e42084d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3e42084d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3e42084d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e42084d{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e42084d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3e42084d{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-67f856b6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-67f856b6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-67f856b6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-67f856b6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-67f856b6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-67f856b6{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-67f856b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-67f856b6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-e916b720.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-e916b720.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e916b720.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e916b720.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e916b720.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-e916b720.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e916b720.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e916b720.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e916b720.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e916b720.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e916b720.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e916b720.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 5100px;height: auto;}.uagb-block-e916b720.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e916b720.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e916b720.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e916b720.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8c2619f3.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-8c2619f3.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-1b5c9ed9 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-1b5c9ed9 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-1b5c9ed9 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-1b5c9ed9 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-container.uagb-block-0836edbd .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0836edbd .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0836edbd .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0836edbd .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0836edbd .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0836edbd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0836edbd{min-height: 229px;box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #fadd05;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 10px;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 10px;}.uagb-block-cc2d3143 .uagb-cta__align-button-after{margin-left: 10px;}.uagb-block-cc2d3143 .uagb-cta__align-button-before{margin-right: 10px;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-cc2d3143 .uagb-cta__content-wrap{text-align: left;}.uagb-block-cc2d3143 .uagb-cta__wrap{width: 70%;text-align: left;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action{text-align: left;}.uagb-block-cc2d3143 .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}.uagb-block-cc2d3143 .uagb-cta__buttons{column-gap: 15px;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-cc2d3143 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 70%;}.uagb-block-cc2d3143 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}.wp-block-uagb-container.uagb-block-f528b674 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f528b674 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f528b674 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f528b674 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f528b674 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f528b674{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f528b674 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f528b674{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 80px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: ;row-gap: 48px;column-gap: 0px;}.uagb-block-5daedf69 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5daedf69 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-5daedf69 .uagb-ifb-icon svg{fill: #333;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5daedf69 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5daedf69 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5daedf69 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5daedf69 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5daedf69 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5daedf69 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5daedf69 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-5daedf69 .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5daedf69 .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-5daedf69 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-5daedf69 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-5daedf69 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-5daedf69 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5daedf69 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-5daedf69.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-5daedf69.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-5daedf69 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-bd486be1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bd486be1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bd486be1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bd486be1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bd486be1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bd486be1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bd486be1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bd486be1{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-image: linear-gradient(to right, #ededed, #ededed), url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/pexels-photo-3862379-3862379.jpg);row-gap: 20px;column-gap: 20px;}.uagb-block-05b13c07 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-05b13c07 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-05b13c07 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-05b13c07 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-05b13c07 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-05b13c07 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-05b13c07.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-05b13c07 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-05b13c07 .uagb-ifb-title{color: var(--ast-global-color-7);margin-bottom: 10px;}.uagb-block-05b13c07 .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-05b13c07 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-05b13c07 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-05b13c07 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-05b13c07 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-05b13c07.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-05b13c07 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{border: 2px solid var(--ast-global-color-0);border-radius: 50%;}.uagb-block-05b13c07 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{border: 2px solid var(--ast-global-color-0);}.uagb-block-05b13c07 .uagb-iconbox-icon-wrap:hover{border: 2px solid ;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-05b13c07 .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ec897ce7 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ec897ce7 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-ec897ce7 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-ec897ce7 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-ec897ce7 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-ec897ce7 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-ec897ce7 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-ec897ce7 .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 10px;}.uagb-block-ec897ce7 .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-ec897ce7 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ec897ce7 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ec897ce7 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ec897ce7 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ec897ce7.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-ec897ce7 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{border: 2px solid var(--ast-global-color-0);border-radius: 50%;}.uagb-block-ec897ce7 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{border: 2px solid var(--ast-global-color-0);}.uagb-block-ec897ce7 .uagb-iconbox-icon-wrap:hover{border: 2px solid ;}.uagb-block-ec897ce7.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ec897ce7 .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-0fdffcab .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0fdffcab .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-0fdffcab .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-0fdffcab .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-0fdffcab .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-0fdffcab .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-0fdffcab .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-0fdffcab .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 10px;}.uagb-block-0fdffcab .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-0fdffcab .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-0fdffcab .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-0fdffcab .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-0fdffcab .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0fdffcab.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-0fdffcab .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{border: 2px solid var(--ast-global-color-0);border-radius: 50%;}.uagb-block-0fdffcab .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{border: 2px solid var(--ast-global-color-0);}.uagb-block-0fdffcab .uagb-iconbox-icon-wrap:hover{border: 2px solid ;}.uagb-block-0fdffcab.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0fdffcab .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b9416cf0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b9416cf0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-b9416cf0 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b9416cf0 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-b9416cf0 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-b9416cf0 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-b9416cf0 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b9416cf0 .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 10px;}.uagb-block-b9416cf0 .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-b9416cf0 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b9416cf0 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b9416cf0 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b9416cf0 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b9416cf0.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-b9416cf0 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{border: 2px solid var(--ast-global-color-0);border-radius: 50%;}.uagb-block-b9416cf0 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{border: 2px solid var(--ast-global-color-0);}.uagb-block-b9416cf0 .uagb-iconbox-icon-wrap:hover{border: 2px solid ;}.uagb-block-b9416cf0.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b9416cf0 .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-2bed7e08 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-2bed7e08 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-2bed7e08 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-2bed7e08 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-2bed7e08 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-2bed7e08 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-2bed7e08 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-2bed7e08 .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 10px;}.uagb-block-2bed7e08 .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-2bed7e08 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-2bed7e08 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-2bed7e08 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-2bed7e08 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2bed7e08.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-2bed7e08 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{border: 2px solid var(--ast-global-color-0);border-radius: 50%;}.uagb-block-2bed7e08 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{border: 2px solid var(--ast-global-color-0);}.uagb-block-2bed7e08 .uagb-iconbox-icon-wrap:hover{border: 2px solid ;}.uagb-block-2bed7e08.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-2bed7e08 .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-29b0edf3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-29b0edf3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-0);}.uagb-block-29b0edf3 .uagb-ifb-icon svg{fill: var(--ast-global-color-0);}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-29b0edf3 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.uagb-block-29b0edf3 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;}.uagb-block-29b0edf3 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 12px;padding-right: 12px;padding-top: 12px;padding-bottom: 12px;border-radius: 0px;}.uagb-block-29b0edf3 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-29b0edf3 .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 10px;}.uagb-block-29b0edf3 .uagb-ifb-desc{color: var(--ast-global-color-2);margin-bottom: 20px;}.uagb-block-29b0edf3 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-29b0edf3 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-29b0edf3 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-29b0edf3 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-29b0edf3.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-29b0edf3 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{border: 2px solid var(--ast-global-color-0);border-radius: 50%;}.uagb-block-29b0edf3 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{border: 2px solid var(--ast-global-color-0);}.uagb-block-29b0edf3 .uagb-iconbox-icon-wrap:hover{border: 2px solid ;}.uagb-block-29b0edf3.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-29b0edf3 .uagb-iconbox-icon-wrap{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 12px;padding-left: 12px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-82860771 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-82860771 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-82860771 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-82860771 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-82860771 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-82860771{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-82860771 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-82860771{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: var(--ast-global-color-5);background-color: ;row-gap: 20px;column-gap: 20px;}.uagb-block-0a68c273 .uagb-marketing-btn__prefix{font-size: 14px;line-height: 2em;margin-top: 0px;}.uagb-block-0a68c273.uagb-marketing-btn__icon-after .uagb-marketing-btn__link svg{margin-left: 10px;}.uagb-block-0a68c273.uagb-marketing-btn__icon-before .uagb-marketing-btn__link svg{margin-right: 10px;}.uagb-block-0a68c273.uagb-marketing-btn__icon-after .uagb-marketing-btn__icon-wrap svg{margin-left: 10px;}.uagb-block-0a68c273.uagb-marketing-btn__icon-before .uagb-marketing-btn__icon-wrap svg{margin-right: 10px;}.uagb-block-0a68c273 .uagb-marketing-btn__title-wrap{align-items: center;}.uagb-block-0a68c273 .uagb-marketing-btn__title-wrap .uagb-marketing-btn__icon-wrap svg{vertical-align: sub;}.uagb-block-0a68c273 svg{width: 20px;height: 20px;}.uagb-block-0a68c273 .uagb-marketing-btn__link svg{fill: var(--ast-global-color-5);}.uagb-block-0a68c273.wp-block-uagb-marketing-button.wp-block-button .wp-block-button__link.uagb-marketing-btn__link{background: var(--ast-global-color-1);}.uagb-block-0a68c273.wp-block-uagb-marketing-button.wp-block-button:not(.is-style-outline) a.wp-block-button__link:not(.has-background){background-color: var(--ast-global-color-1);}.uagb-block-0a68c273.wp-block-uagb-marketing-button.wp-block-button:not(.is-style-outline) .wp-block-button__link.uagb-marketing-btn__link:hover{background: var(--ast-global-color-0);}.uagb-block-0a68c273.wp-block-uagb-marketing-button.wp-block-button:not(.is-style-outline) .wp-block-button__link.uagb-marketing-btn__link:focus{background: var(--ast-global-color-0);}.uagb-block-0a68c273 .uagb-marketing-btn__link{background: var(--ast-global-color-1);}.uagb-block-0a68c273 p.uagb-marketing-btn__prefix{color: var(--ast-global-color-5);}.uagb-block-0a68c273 .uagb-marketing-btn__link.wp-block-button__link{padding-left: 33px;padding-right: 33px;padding-top: 8px;padding-bottom: 8px;border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 100px;border-top-right-radius: 100px;border-bottom-left-radius: 100px;border-bottom-right-radius: 100px;border-color: #333;border-style: solid;}.uagb-block-0a68c273 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 33px;padding-right: 33px;padding-top: 8px;padding-bottom: 8px;border-top-width: 2px;border-left-width: 2px;border-right-width: 2px;border-bottom-width: 2px;border-top-left-radius: 100px;border-top-right-radius: 100px;border-bottom-left-radius: 100px;border-bottom-right-radius: 100px;border-color: #333;border-style: solid;}.uagb-block-0a68c273 .uagb-marketing-btn__title{font-size: 20px;}.wp-block-uagb-container.uagb-block-933ce29f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-933ce29f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-933ce29f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-933ce29f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-933ce29f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-933ce29f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-933ce29f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-933ce29f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-420957bb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-420957bb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-420957bb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-420957bb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-420957bb .uagb-container__video-wrap video{opacity: 0.25;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-420957bb{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-420957bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 154px;column-gap: 135px;}.wp-block-uagb-container.uagb-block-420957bb{box-shadow: -3px 18px 40px -10px #00000070 ;padding-top: 300px;padding-bottom: 329px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/Navepreingeniada-scaled.jpg);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 154px;column-gap: 135px;}.wp-block-uagb-container.uagb-block-420957bb::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: rgba(26,44,61,0.93);opacity: 0.75;}.wp-block-uagb-container.uagb-block-973044c4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-973044c4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-973044c4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-973044c4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-973044c4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-973044c4{max-width: 75%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-973044c4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-973044c4{box-shadow: 0px 0px   #00000070 ;padding-top: 60px;padding-bottom: 60px;padding-left: 60px;padding-right: 19px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: -20px;margin-right: 20px;overflow: visible;order: initial;border-color: inherit;background-color: #fbd810;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-fb345f9d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fb345f9d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb345f9d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb345f9d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb345f9d .uagb-heading-text{font-size: 35px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 12px;text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 50px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 12px;line-height: em;}.wp-block-uagb-icon-list.uagb-block-f755cec1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-ed470cbd.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-ed470cbd.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-f1c057f4.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-f1c057f4.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2ba4170d.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2ba4170d.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-aad0a1f2.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-aad0a1f2.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.wp-block-uagb-container.uagb-block-94d98ee3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-94d98ee3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-94d98ee3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-94d98ee3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-94d98ee3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-94d98ee3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-94d98ee3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1115px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-94d98ee3{min-height: 196px;box-shadow: 0px 18px 40px -10px #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);row-gap: 32px;column-gap: 40px;}.uagb-block-33018f89.wp-block-uagb-image-gallery{padding:    ;visibility: hidden;}.uagb-block-33018f89 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-33018f89 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-33018f89 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-33018f89 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-33018f89 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-33018f89 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-33018f89 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-33018f89 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-33018f89 .spectra-image-gallery__layout--grid{grid-gap: 80px;}.uagb-block-33018f89 .spectra-image-gallery__layout--isogrid{margin: -40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--masonry{margin: -40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--tiled{grid-gap: 80px;}.uagb-block-33018f89 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-33018f89spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-33018f89 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-33b2e460 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-33b2e460 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-33b2e460 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-33b2e460 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-33b2e460 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-33b2e460{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-33b2e460 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-33b2e460{box-shadow: 0px 0px   #00000070 ;padding-top: 150px;padding-bottom: 350px;padding-left: 0px;padding-right: 0px;margin-top: -50px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/Diseno-sin-titulo-13.png);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-dd5d62ed .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd5d62ed .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd5d62ed .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd5d62ed .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd5d62ed .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd5d62ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd5d62ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 110px;column-gap: 94px;}.wp-block-uagb-container.uagb-block-dd5d62ed{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 200px;padding-right: 200px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: -400px;margin-right: -400px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-clip: padding-box;row-gap: 110px;column-gap: 94px;}.wp-block-uagb-container.uagb-block-3ac9af46 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3ac9af46 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3ac9af46 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3ac9af46 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3ac9af46 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ac9af46{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ac9af46 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3ac9af46{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-64d3b7bb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-64d3b7bb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-64d3b7bb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-64d3b7bb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-64d3b7bb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-64d3b7bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-64d3b7bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-64d3b7bb{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: -50px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5eb8e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5eb8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-01a5eb8e{box-shadow: 0px 0px   #00000070 ;padding-top: 80px;padding-bottom: -100px;padding-left: 0px;padding-right: 0px;margin-top: -80px !important;margin-bottom: 300px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3c79a888 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3c79a888 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3c79a888 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3c79a888 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3c79a888 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3c79a888{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3c79a888 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3c79a888{box-shadow: 0px 0px   #00000070 ;padding-top: 80px;padding-bottom: -50px;padding-left: 0px;padding-right: 0px;margin-top: 50px !important;margin-bottom: 300px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6b1f9db{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6b1f9db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a6b1f9db{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: #f5f5f5;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b8ab2e1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b8ab2e1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3b8ab2e1{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b0aef8d0.wp-block-uagb-container{color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-block-b0aef8d0.wp-block-uagb-container *{color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0aef8d0{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0aef8d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 30px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b0aef8d0{box-shadow: 0px 0px   #00000070 ;padding-top: 64px;padding-bottom: 0px;padding-left: 64px;padding-right: 64px;margin-top: -55px !important;margin-bottom: -250px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 30px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-37fe9e23{width: 100%;}.wp-block-uagb-container.uagb-block-37fe9e23{padding-top: 150px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/nave_industrial.jpeg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-37fe9e23::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-1);opacity: 0.85;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad563c4a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad563c4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ad563c4a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e42084d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e42084d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3e42084d{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-67f856b6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-67f856b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-67f856b6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-e916b720.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 5100px;height: auto;}.uagb-block-8c2619f3.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-8c2619f3.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0836edbd{width: 100%;}.wp-block-uagb-container.uagb-block-0836edbd{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #fadd05;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-cc2d3143.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-cc2d3143 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-cc2d3143 .uagb-cta__wrap{text-align: center;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f528b674{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f528b674 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f528b674{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: ;row-gap: 40px;column-gap: 0px;}.uagb-block-5daedf69 .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5daedf69 .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5daedf69 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5daedf69 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-5daedf69 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-5daedf69 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5daedf69 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5daedf69.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-5daedf69.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bd486be1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bd486be1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bd486be1{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: linear-gradient(to right, #ededed, #ededed), url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/pexels-photo-3862379-3862379.jpg);}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-05b13c07 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-05b13c07 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-05b13c07 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-05b13c07.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ec897ce7 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ec897ce7 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ec897ce7 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0fdffcab .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0fdffcab .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0fdffcab .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b9416cf0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b9416cf0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b9416cf0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2bed7e08 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-2bed7e08 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-2bed7e08 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-29b0edf3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-29b0edf3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-29b0edf3 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap{border-color: var(--ast-global-color-5);}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-82860771{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-82860771 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-82860771{padding-top: 0px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-color: var(--ast-global-color-5);background-color: ;}.uagb-block-0a68c273 .uagb-marketing-btn__prefix{font-size: 14px;}.uagb-block-0a68c273 .uagb-marketing-btn__link.wp-block-button__link{border-style: solid;border-color: #333;}.uagb-block-0a68c273 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-style: solid;border-color: #333;}.uagb-block-0a68c273 .uagb-marketing-btn__title{font-size: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-933ce29f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-933ce29f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-933ce29f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-420957bb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-420957bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-420957bb{padding-top: 300px;padding-bottom: 329px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/Navepreingeniada-scaled.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-420957bb::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: rgba(26,44,61,0.93);opacity: 0.75;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-973044c4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-973044c4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-973044c4{padding-top: 51px;padding-bottom: 0px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: -20px;margin-right: 20px;order: initial;background-color: #fbd810;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-f755cec1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-94d98ee3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-94d98ee3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-94d98ee3{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);}.uagb-block-33018f89.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-33018f89 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-33018f89 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-33018f89 .spectra-image-gallery__layout--grid{grid-gap: 80px;}.uagb-block-33018f89 .spectra-image-gallery__layout--isogrid{margin: -40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--masonry{margin: -40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 80px;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -80px;}.uagb-block-33018f89 .spectra-image-gallery__layout--tiled{grid-gap: 80px;}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-33b2e460{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-33b2e460 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-33b2e460{padding-top: 150px;padding-bottom: 350px;padding-left: 0px;padding-right: 0px;margin-top: -50px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/Diseno-sin-titulo-13.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd5d62ed{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd5d62ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-dd5d62ed{padding-top: 0px;padding-bottom: 0px;padding-left: 200px;padding-right: 200px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: -400px;margin-right: -400px;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ac9af46{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ac9af46 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3ac9af46{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-64d3b7bb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-64d3b7bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-64d3b7bb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: -50px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5eb8e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5eb8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-01a5eb8e{padding-top: 80px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: -80px !important;margin-bottom: 300px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3c79a888{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3c79a888 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3c79a888{padding-top: 80px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 50px !important;margin-bottom: 300px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6b1f9db{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6b1f9db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a6b1f9db{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top: 0px !important;margin-bottom: -20px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f5f5f5;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b8ab2e1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b8ab2e1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3b8ab2e1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0aef8d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0aef8d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b0aef8d0{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top: 0px !important;margin-bottom: -180px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-37fe9e23{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-37fe9e23{padding-top: 100px;padding-bottom: 50px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/nave_industrial.jpeg);background-clip: padding-box;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-37fe9e23::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-1);opacity: 0.85;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading {padding-top: 20px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ad563c4a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ad563c4a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ad563c4a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e42084d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e42084d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3e42084d{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-67f856b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-67f856b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-67f856b6{padding-top: 0px;padding-bottom: 80px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-e916b720.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 5100px;height: auto;}.uagb-block-8c2619f3.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-8c2619f3.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0836edbd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0836edbd{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #fadd05;flex-wrap: wrap;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-cc2d3143.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-cc2d3143 .uagb-cta__buttons{justify-content: center;}.uagb-block-cc2d3143 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}.uagb-block-cc2d3143 .uagb-cta__wrap{text-align: center;}.uagb-block-cc2d3143.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f528b674{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f528b674 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f528b674{padding-top: 64px;padding-bottom: 40px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: ;}.uagb-block-5daedf69 .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5daedf69 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-5daedf69 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5daedf69 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5daedf69 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5daedf69 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-5daedf69 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-5daedf69.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-5daedf69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bd486be1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bd486be1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bd486be1{padding-top: 50px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: linear-gradient(to right, #ededed, #ededed), url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/pexels-photo-3862379-3862379.jpg);}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07 .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-05b13c07 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-05b13c07 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-05b13c07 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-05b13c07.uagb-infobox__content-wrap{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);}.uagb-block-05b13c07.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-05b13c07.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07 .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-05b13c07.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7 .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ec897ce7 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ec897ce7 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ec897ce7 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ec897ce7.uagb-infobox__content-wrap{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);}.uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7 .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-ec897ce7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0fdffcab .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0fdffcab .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0fdffcab .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0fdffcab.uagb-infobox__content-wrap{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);}.uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-0fdffcab.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0 .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b9416cf0 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-b9416cf0 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-b9416cf0 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b9416cf0.uagb-infobox__content-wrap{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);}.uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0 .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-b9416cf0.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08 .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2bed7e08 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-2bed7e08 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-2bed7e08 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2bed7e08.uagb-infobox__content-wrap{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);}.uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08 .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-2bed7e08.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3 .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-29b0edf3 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-29b0edf3 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-29b0edf3 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-29b0edf3.uagb-infobox__content-wrap{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: var(--ast-global-color-5);}.uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3 .uagb-ifb-content > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-29b0edf3.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-82860771{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-82860771 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-82860771{padding-top: 0px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-color: var(--ast-global-color-5);background-color: ;}.uagb-block-0a68c273 .uagb-marketing-btn__prefix{font-size: 14px;line-height: 1.3em;}.uagb-block-0a68c273.wp-block-uagb-marketing-button.wp-block-button .uagb-marketing-btn__link{border-style: solid;border-color: #333;}.uagb-block-0a68c273 .uagb-marketing-btn__wrap .uagb-marketing-btn__link{padding-left: 20px;padding-right: 20px;padding-top: 8px;padding-bottom: 8px;border-style: solid;border-color: #333;}.uagb-block-0a68c273 .uagb-marketing-btn__title{font-size: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-933ce29f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-933ce29f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-933ce29f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-420957bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-420957bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-420957bb{padding-top: 300px;padding-bottom: 329px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: -100px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/11\/Navepreingeniada-scaled.jpg);background-clip: padding-box;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-420957bb::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: rgba(26,44,61,0.93);opacity: 0.75;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-973044c4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-973044c4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-973044c4{padding-top: 51px;padding-bottom: 0px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #fbd810;flex-wrap: wrap;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-f755cec1 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-f755cec1.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-94d98ee3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-94d98ee3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-94d98ee3{padding-top: 40px;padding-bottom: 40px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 20px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);}.uagb-block-33018f89.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-33018f89 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-33018f89 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-33018f89 .spectra-image-gallery__layout--grid{grid-gap: 80px;}.uagb-block-33018f89 .spectra-image-gallery__layout--isogrid{margin: -40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--masonry{margin: -40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 40px;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 80px;}.uagb-block-33018f89 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -80px;}.uagb-block-33018f89 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 80px;}.uagb-block-33018f89 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-33018f89+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-33b2e460{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-33b2e460 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-33b2e460{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/12\/Diseno-sin-titulo-13.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd5d62ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd5d62ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-dd5d62ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3ac9af46{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3ac9af46 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3ac9af46{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-64d3b7bb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-64d3b7bb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-64d3b7bb{padding-top: 0px;padding-bottom: 80px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5eb8e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5eb8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 426px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-01a5eb8e{padding-top: 80px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 80px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3c79a888{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3c79a888 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 426px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-3c79a888{padding-top: 80px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 80px !important;margin-bottom: 80px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6b1f9db{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6b1f9db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a6b1f9db{padding-top: 100px;padding-bottom: 100px;padding-left: 25px;padding-right: 25px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f5f5f5;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b8ab2e1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b8ab2e1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3b8ab2e1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0aef8d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0aef8d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b0aef8d0{padding-top: 25px;padding-bottom: 25px;padding-left: 25px;padding-right: 25px;margin-top: -55px !important;margin-bottom: -55px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);flex-wrap: wrap;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.uagb-block-.wp-block-spectra-pro-login{width: 100%;box-shadow: 0px 0px   #00000070 ;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .wp-block-spectra-pro-login__logged-in-message{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login label{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login input{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__recaptcha{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass button span{font-size: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass label{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass input{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__forgetmenot{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a{font-style: normal;color: 1;margin: unset;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a:hover{color: 1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form-username-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form__user-pass .spectra-pro-login-form-pass-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-rememberme label{font-style: normal;margin: unset;}.uagb-block- .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark{width: 20px;height: 20px;border-width: 1px;border-radius: 2px;}.uagb-block- .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark:after{font-size: 10px;}.uagb-block- .spectra-pro-login-form-rememberme input[type=\"checkbox\"]:focus + .spectra-pro-login-form-rememberme__checkmark{box-shadow: 0 0 0 1px #2271b1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-register:hover{color: 1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__submit{justify-content: full;margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{font-style: normal;column-gap: 5px;width: 100%;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__success{border-left-color: #008000;background-color: #d4edda;color: #155724;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__error{border-left-color: #ff0000;background-color: #f8d7da;color: #721c24;}.uagb-block- .wp-block-spectra-pro-login-info{font-style: normal;}.uagb-block- .wp-block-spectra-pro-login-info a{color: 1;}.uagb-block- .wp-block-spectra-pro-login__logged-in-message a{color: 1;}.uagb-block- .wp-block-spectra-pro-login__logged-in-message a:hover{color: 1;}.wp-block-uagb-advanced-heading.uagb-block-e48442b8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e48442b8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e48442b8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e48442b8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.uagb-block-.wp-block-spectra-pro-login{width: 100%;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}@media only screen and (max-width: 767px) {.uagb-block-.wp-block-spectra-pro-login{width: 100%;padding-top: 20px;padding-right: 30px;padding-bottom: 20px;padding-left: 30px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login{width: 100%;box-shadow: 0px 0px   #00000070 ;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-login{margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .wp-block-spectra-pro-login__logged-in-message{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-login label{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-login input{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__recaptcha{margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass{margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass button span{font-size: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass label{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass input{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__forgetmenot{margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a{font-style: normal;color: 1;margin: unset;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a:hover{color: 1;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form-username-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form__user-pass .spectra-pro-login-form-pass-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-rememberme label{font-style: normal;margin: unset;}.uagb-block-ff5fb2b1 .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark{width: 20px;height: 20px;border-width: 1px;border-radius: 2px;}.uagb-block-ff5fb2b1 .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark:after{font-size: 10px;}.uagb-block-ff5fb2b1 .spectra-pro-login-form-rememberme input[type=\"checkbox\"]:focus + .spectra-pro-login-form-rememberme__checkmark{box-shadow: 0 0 0 1px #2271b1;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-register:hover{color: 1;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__submit{justify-content: full;margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{font-style: normal;column-gap: 5px;width: 100%;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__success{border-left-color: #008000;background-color: #d4edda;color: #155724;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__error{border-left-color: #ff0000;background-color: #f8d7da;color: #721c24;}.uagb-block-ff5fb2b1 .wp-block-spectra-pro-login-info{font-style: normal;}.uagb-block-ff5fb2b1 .wp-block-spectra-pro-login-info a{color: 1;}.uagb-block-ff5fb2b1 .wp-block-spectra-pro-login__logged-in-message a{color: 1;}.uagb-block-ff5fb2b1 .wp-block-spectra-pro-login__logged-in-message a:hover{color: 1;}.wp-block-uagb-advanced-heading.uagb-block-971a0071.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-971a0071.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-971a0071.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-971a0071.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.uagb-block-ff5fb2b1.wp-block-spectra-pro-login{width: 100%;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}@media only screen and (max-width: 767px) {.uagb-block-ff5fb2b1.wp-block-spectra-pro-login{width: 100%;padding-top: 20px;padding-right: 30px;padding-bottom: 20px;padding-left: 30px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}.uagb-block-.wp-block-spectra-pro-login{width: 100%;box-shadow: 0px 0px   #00000070 ;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .wp-block-spectra-pro-login__logged-in-message{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login label{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login input{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__recaptcha{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass button span{font-size: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass label{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass input{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__forgetmenot{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a{font-style: normal;color: 1;margin: unset;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a:hover{color: 1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form-username-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form__user-pass .spectra-pro-login-form-pass-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-rememberme label{font-style: normal;margin: unset;}.uagb-block- .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark{width: 20px;height: 20px;border-width: 1px;border-radius: 2px;}.uagb-block- .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark:after{font-size: 10px;}.uagb-block- .spectra-pro-login-form-rememberme input[type=\"checkbox\"]:focus + .spectra-pro-login-form-rememberme__checkmark{box-shadow: 0 0 0 1px #2271b1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-register:hover{color: 1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__submit{justify-content: full;margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{font-style: normal;column-gap: 5px;width: 100%;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__success{border-left-color: #008000;background-color: #d4edda;color: #155724;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__error{border-left-color: #ff0000;background-color: #f8d7da;color: #721c24;}.uagb-block- .wp-block-spectra-pro-login-info{font-style: normal;}.uagb-block- .wp-block-spectra-pro-login-info a{color: 1;}.uagb-block- .wp-block-spectra-pro-login__logged-in-message a{color: 1;}.uagb-block- .wp-block-spectra-pro-login__logged-in-message a:hover{color: 1;}.wp-block-uagb-advanced-heading.uagb-block-634f5264.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-634f5264.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-634f5264.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-634f5264.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.uagb-block-.wp-block-spectra-pro-login{width: 100%;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}@media only screen and (max-width: 767px) {.uagb-block-.wp-block-spectra-pro-login{width: 100%;padding-top: 20px;padding-right: 30px;padding-bottom: 20px;padding-left: 30px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}\";s:2:\"js\";s:3328:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-1b5c9ed9' );\n});\njQuery(document).ready(function () {\n\t\t\t\tlet scope = jQuery(\".wp-block-uagb-image-gallery.uagb-block-33018f89\");\n\t\t\t\tif ( scope.length ) { \n\t\t\t\t\tscope.css(\"visibility\", \"visible\");\n\t\t\t\t\tlet getSlickCarousel = scope.find(\".uagb-slick-carousel\");\n\t\t\t\t\tif( getSlickCarousel.length ) {\n\t\t\t\t\t\tgetSlickCarousel.slick({\"arrows\":true,\"dots\":true,\"initialSlide\":0,\"infinite\":true,\"autoplay\":true,\"autoplaySpeed\":2445,\"pauseOnHover\":true,\"speed\":500,\"slidesToShow\":3,\"prevArrow\":\"<button type='button' data-role='none' class='spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--carousel slick-prev slick-arrow' aria-label='Previous' tabindex='0' role='button'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 256 512' width='24' height='24'><path d='M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z'><\/path><\/svg><\/button>\",\"nextArrow\":\"<button type='button' data-role='none' class='spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--carousel slick-next slick-arrow' aria-label='Previous' tabindex='0' role='button'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 256 512' width='24' height='24'><path d='M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z'><\/path><\/svg><\/button>\",\"rtl\":false,\"responsive\":[{\"breakpoint\":1024,\"settings\":{\"slidesToShow\":2}},{\"breakpoint\":767,\"settings\":{\"slidesToShow\":2}}]});\n\t\t\t\t\t}\n\t\t\t\t}\n\t\t\t});window.addEventListener( 'load', function() {\n\tUAGBLogin.init( '#spectra-pro-login-form-', '.uagb-block-', {\"ajax_url\":\"https:\/\/jansametal.com\/wp-admin\/admin-ajax.php\",\"post_id\":10329,\"block_id\":\"\",\"enableReCaptcha\":false,\"recaptchaVersion\":\"v2\",\"recaptchaSiteKey\":\"\",\"loginRedirectURL\":\"https:\/\/jansametal.com\/en\/\",\"logoutRedirectURL\":\"https:\/\/jansametal.com\/en\/\",\"this_field_error_msg\":{\"username\":\"Nombre de usuario o email cannot be blank.\",\"password\":\"Contraseu00f1a cannot be blank.\"}} );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBLogin.init( '#spectra-pro-login-form-ff5fb2b1', '.uagb-block-ff5fb2b1', {\"ajax_url\":\"https:\/\/jansametal.com\/wp-admin\/admin-ajax.php\",\"post_id\":10329,\"block_id\":\"ff5fb2b1\",\"enableReCaptcha\":false,\"recaptchaVersion\":\"v2\",\"recaptchaSiteKey\":\"\",\"loginRedirectURL\":\"https:\/\/jansametal.com\/en\/\",\"logoutRedirectURL\":\"https:\/\/jansametal.com\/en\/\",\"this_field_error_msg\":{\"username\":\"Username or Email Address cannot be blank.\",\"password\":\"Password cannot be blank.\"}} );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBLogin.init( '#spectra-pro-login-form-', '.uagb-block-', {\"ajax_url\":\"https:\/\/jansametal.com\/wp-admin\/admin-ajax.php\",\"post_id\":10329,\"block_id\":\"\",\"enableReCaptcha\":false,\"recaptchaVersion\":\"v2\",\"recaptchaSiteKey\":\"\",\"loginRedirectURL\":\"https:\/\/jansametal.com\/en\/\",\"logoutRedirectURL\":\"https:\/\/jansametal.com\/en\/\",\"this_field_error_msg\":{\"username\":\"Username or Email Address cannot be blank.\",\"password\":\"Password cannot be blank.\"}} );\n});\n });\";s:18:\"current_block_list\";a:26:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:4;s:12:\"core\/heading\";i:5;s:14:\"core\/paragraph\";i:7;s:10:\"uagb\/image\";i:8;s:12:\"uagb\/buttons\";i:9;s:18:\"uagb\/buttons-child\";i:11;s:19:\"uagb\/call-to-action\";i:13;s:13:\"uagb\/info-box\";i:15;s:12:\"core\/columns\";i:16;s:11:\"core\/column\";i:18;s:21:\"uagb\/marketing-button\";i:19;s:14:\"uagb\/icon-list\";i:20;s:20:\"uagb\/icon-list-child\";i:22;s:18:\"uagb\/image-gallery\";i:23;s:8:\"wpsp\/faq\";i:24;s:14:\"wpsp\/faq-child\";i:28;s:15:\"uagb\/cf7-styler\";i:29;s:10:\"core\/group\";i:30;s:20:\"core\/latest-comments\";i:31;s:13:\"core\/archives\";i:32;s:10:\"uagb\/login\";i:33;s:10:\"core\/image\";i:34;s:11:\"core\/search\";i:35;s:17:\"core\/latest-posts\";i:36;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788341466\";s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wpca-thumb":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/jansametal.com\/en\/author\/anjo\/"},"uagb_comment_info":0,"uagb_excerpt":"Enclosures Metal structure enclosures and roofing designed to protect your building, optimize its performance and ensure long-term durability. Imagine a building roof capable of withstanding any weather condition, maintaining safety without sacrificing modern design. From industrial enclosures to roofing for industrial buildings, our solutions are built to last and deliver maximum performance. Forget about leaks,&hellip;","_links":{"self":[{"href":"https:\/\/jansametal.com\/en\/wp-json\/wp\/v2\/pages\/10329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jansametal.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jansametal.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jansametal.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jansametal.com\/en\/wp-json\/wp\/v2\/comments?post=10329"}],"version-history":[{"count":9,"href":"https:\/\/jansametal.com\/en\/wp-json\/wp\/v2\/pages\/10329\/revisions"}],"predecessor-version":[{"id":14715,"href":"https:\/\/jansametal.com\/en\/wp-json\/wp\/v2\/pages\/10329\/revisions\/14715"}],"wp:attachment":[{"href":"https:\/\/jansametal.com\/en\/wp-json\/wp\/v2\/media?parent=10329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}