{"id":10579,"date":"2024-10-25T11:03:38","date_gmt":"2024-10-25T09:03:38","guid":{"rendered":"https:\/\/jansa.serveistic.com\/ressources\/"},"modified":"2026-04-30T06:50:31","modified_gmt":"2026-04-30T04:50:31","slug":"ressources","status":"publish","type":"page","link":"https:\/\/jansametal.com\/fr\/ressources\/","title":{"rendered":"Ressources"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-37fe9e23 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d36b578f\"><h1 class=\"uagb-heading-text\">Ressources structures m\u00e9talliques<\/h1><\/div>\n<\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-e4be775b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-9a4bad7b\">\n<div class=\"wp-block-uagb-info-box uagb-block-639134ac uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/jansametal.com\/fr\/category\/blog\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\"><\/a><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Blog de Jansa Metal<\/h3><\/div><p class=\"uagb-ifb-desc\">Publications d&rsquo;int\u00e9r\u00eat sur la construction de b\u00e2timents avec une structure en acier<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-14f4c019 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"#\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\"><\/a><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Manuels<\/h3><\/div><p class=\"uagb-ifb-desc\">Manuels d&rsquo;utilisation et d&rsquo;entretien des composants.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5807f0db\">\n<div class=\"wp-block-uagb-info-box uagb-block-178fa41f uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/jansametal.com\/fr\/pieces-dune-structure-metallique\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\"><\/a><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">D\u00e9tails de construction<\/h3><\/div><p class=\"uagb-ifb-desc\">Visualisation typique de b\u00e2timents construits avec structure m\u00e9tallique par Jansa Metal.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-e09bad92 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-left uagb-infobox-left uagb-infobox-stacked-mobile uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/jansametal.com\/fr\/rendus-et-videos\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\"><\/a><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><\/div><\/div><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Vid\u00e9os<\/h3><\/div><p class=\"uagb-ifb-desc\">Vid\u00e9os et rendus (renderizaciones) de projets de construction avec structure m\u00e9tallique.<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-01a5eb8e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a6b1f9db\">\n<div class=\"wp-block-uagb-container uagb-block-3b8ab2e1\">\n<h2 class=\"wp-block-heading\"><strong>Pr\u00eat pour la premi\u00e8re \u00e9tape ?<\/strong> Contactez-nous !<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tout grand projet commence par une conversation. <strong>Contactez-nous et d\u00e9couvrez comment nous<\/strong> pouvons concr\u00e9tiser votre id\u00e9e, avec des structures m\u00e9talliques aussi solides que vos attentes.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b0aef8d0\">\n<div class=\"wp-block-uagb-container uagb-block-c8e181d6 alignwide uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-2095f831\">\t\t\t\t<div class = \"wp-block-uagb-cf7-styler uagb-cf7-styler__outer-wrap uagb-block-0bbd5a13   \">\n\t\t\t\t\t<div class = \"uagb-cf7-styler__align-left uagb-cf7-styler__field-style-underline uagb-cf7-styler__btn-align-center uagb-cf7-styler__btn-align-tablet- uagb-cf7-styler__btn-align-mobile- uagb-cf7-styler__highlight-style-default uagb-cf7-styler__check-style-enabled\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13378-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"13378\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/10579#wpcf7-f13378-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"13378\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13378-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Pr\u00e9nom*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Nom*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"apellido\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"apellido\" \/><\/span> <\/label>\n<\/p>\n<p><label> Adresse e-mail*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> T\u00e9l\u00e9phone<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span><\/label>\n<\/p>\n<p><label> Objet*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"term_and_conditions\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"term_and_conditions\" value=\"1\" class=\"required\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">J\u2019ai lu et j\u2019accepte <a href=\"..\/es\/aviso-legal\/\">l\u2019avis l\u00e9gal et les conditions d\u2019utilisation<\/a>, ainsi que les<a href=\"..\/es\/politica-de-privacidad\/\"> politiques de confidentialit\u00e9<\/a> et de<a href=\"..\/es\/politica-de-cookies\/\"> cookies<\/a>.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n\n<!--[cf7sr-simple-recaptcha] -->\n\n<!-- [anr_nocaptcha g-recaptcha-response] -->\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ressources structures m\u00e9talliques Pr\u00eat pour la premi\u00e8re \u00e9tape ? Contactez-nous ! Tout grand projet commence par une conversation. Contactez-nous et d\u00e9couvrez comment nous pouvons concr\u00e9tiser votre id\u00e9e, avec des structures m\u00e9talliques aussi solides que vos attentes.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"plain-container","ast-site-content-layout":"normal-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-10579","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"site-post-title":["disabled"],"site-sidebar-layout":["no-sidebar"],"site-content-layout":["plain-container"],"ast-featured-img":["disabled"],"theme-transparent-header-meta":["enabled"],"ast-site-content-layout":["normal-width-container"],"site-content-style":["unboxed"],"site-sidebar-style":["unboxed"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_last_translation_edit_mode":["translation-editor"],"_wp_page_template":[""],"rank_math_internal_links_processed":["1"],"_wpml_word_count":["117"],"_edit_lock":["1771244854:6"],"rank_math_seo_score":["60"],"_uag_custom_page_level_css":[""],"ast-disable-related-posts":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-4)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"_edit_last":["6"],"rank_math_analytic_object_id":["168"],"rank_math_title":["Ressources structures m\u00e9talliques | Jansa Metal"],"rank_math_description":["Ressources sur les structures m\u00e9talliques avec des rendus, des vid\u00e9os, des manuels et de la documentation r\u00e9elle sur les projets de Jansa Metal, de l'ing\u00e9nierie \u00e0 l'assemblage."],"rank_math_focus_keyword":["ressources structures m\u00e9talliques"],"_uag_css_file_name":["uag-css-10579.css"],"_uag_js_file_name":["uag-js-10579.js"],"_uag_page_assets":["a:9:{s:3:\"css\";s:118686:\"\ufeff.wp-block-uagb-cf7-styler input[type=text],.wp-block-uagb-cf7-styler input[type=password],.wp-block-uagb-cf7-styler input[type=date],.wp-block-uagb-cf7-styler input[type=datetime],.wp-block-uagb-cf7-styler input[type=datetime-local],.wp-block-uagb-cf7-styler input[type=email],.wp-block-uagb-cf7-styler input[type=month],.wp-block-uagb-cf7-styler input[type=number],.wp-block-uagb-cf7-styler input[type=search],.wp-block-uagb-cf7-styler input[type=tel],.wp-block-uagb-cf7-styler input[type=time],.wp-block-uagb-cf7-styler input[type=url],.wp-block-uagb-cf7-styler input[type=week]{min-height:30px;line-height:30px}.wp-block-uagb-cf7-styler textarea{resize:vertical}.wp-block-uagb-cf7-styler .wpcf7 *,.wp-block-uagb-cf7-styler .wpcf7 ::after,.wp-block-uagb-cf7-styler .wpcf7 ::before{-webkit-box-sizing:border-box;box-sizing:border-box}.wp-block-uagb-cf7-styler span.wpcf7-list-item-label::before,.wp-block-uagb-cf7-styler span.wpcf7-list-item-label::after{content:\" \"}.wp-block-uagb-cf7-styler .wpcf7-acceptance input[type=checkbox]+span::before,.wp-block-uagb-cf7-styler .wpcf7-checkbox input[type=checkbox]+span::before,.wp-block-uagb-cf7-styler .wpcf7-radio input[type=radio]+span::before{display:inline-block;vertical-align:middle;width:15px;height:15px;margin-right:10px;border-color:#eaeaea;border-style:solid;border-width:1px 1px 1px 1px;text-align:center;content:\"\"}.wp-block-uagb-cf7-styler span.wpcf7-list-item{display:inline-block;margin:0 1em 0 0}.wp-block-uagb-cf7-styler .wpcf7-acceptance input[type=checkbox]:checked+span::before,.wp-block-uagb-cf7-styler .wpcf7-checkbox input[type=checkbox]:checked+span::before{line-height:1.2;content:\"\u2714\"}.wp-block-uagb-cf7-styler .wpcf7-acceptance input[type=checkbox]+span::before,.wp-block-uagb-cf7-styler .wpcf7-acceptance input[type=checkbox]:checked+span::before,.wp-block-uagb-cf7-styler .wpcf7-checkbox input[type=checkbox]+span::before,.wp-block-uagb-cf7-styler .wpcf7-checkbox input[type=checkbox]:checked+span::before,.wp-block-uagb-cf7-styler .wpcf7-radio input[type=radio]+span::before{-webkit-box-sizing:content-box;-moz-box-sizing:content-box;box-sizing:content-box}.wp-block-uagb-cf7-styler input[type=checkbox]:checked+span::before{font-size:-webkit-calc(12px \/ 1.2);font-size:10px}.wp-block-uagb-cf7-styler .wpcf7-radio input[type=radio]+span::before{-webkit-border-radius:100%;border-radius:100%}.wp-block-uagb-cf7-styler .uagb-cf7-styler__field-style-box .wpcf7-radio input[type=radio]:checked+span::before,.wp-block-uagb-cf7-styler .uagb-cf7-styler__field-style-underline .wpcf7-radio input[type=radio]:checked+span::before{box-shadow:inset 0 0 0 4px #fafafa;background-color:#545454}.wp-block-uagb-cf7-styler .uagb-cf7-styler__btn-align-justify input.wpcf7-form-control.wpcf7-submit,.wp-block-uagb-cf7-styler .uagb-cf7-styler__btn-align-left input.wpcf7-form-control.wpcf7-submit,.wp-block-uagb-cf7-styler .uagb-cf7-styler__btn-align-right input.wpcf7-form-control.wpcf7-submit,.wp-block-uagb-cf7-styler .uagb-cf7-styler__btn-align-center input.wpcf7-form-control.wpcf7-submit{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;width:auto;padding:10px 25px;background:rgba(0,0,0,0);border-color:#333;border-width:1px;line-height:16px;-js-display:flex}.wp-block-uagb-cf7-styler .wpcf7 input[type=checkbox],.wp-block-uagb-cf7-styler .wpcf7 input[type=radio]{display:none}.wp-block-uagb-cf7-styler .wpcf7 select{height:auto;padding:10px;-webkit-appearance:menulist-button;-moz-appearance:menulist-button}.wp-block-uagb-cf7-styler select.wpcf7-form-control.wpcf7-select[multiple=multiple]{padding:0}.wp-block-uagb-cf7-styler .wpcf7 select option{padding:10px}.wp-block-uagb-cf7-styler .uagb-cf7-styler__highlight-style-bottom_right span.wpcf7-not-valid-tip{display:block;padding:.1em .5em;margin-top:5px;border-radius:2px;font-size:.9em;-webkit-border-radius:2px;width:fit-content;margin-left:auto;margin-right:0}.wp-block-uagb-cf7-styler .wpcf7 input[type=number]{height:auto}.wp-block-uagb-cf7-styler .wpcf7 input.wpcf7-date{-webkit-appearance:none}.wp-block-uagb-cf7-styler .wpcf7-spinner{margin-top:25px}@media(min-width: 769px){.wp-block-uagb-cf7-styler .uagb-cf7_styler-col>p{-js-display:flex;display:-webkit-box;display:-webkit-flex;display:-moz-box;display:-ms-flexbox;display:flex;flex-wrap:wrap;width:100%}.wp-block-uagb-cf7-styler .uagb-cf7_styler-col label,.wp-block-uagb-cf7-styler .uagb-cf7_styler-col>p>span{-webkit-box-flex:1;-webkit-flex-grow:1;-moz-box-flex:1;-ms-flex-positive:1;flex:1;flex-grow:1}.wp-block-uagb-cf7-styler .uagb-cf7_styler-col br{display:none}.wp-block-uagb-cf7-styler .uagb-cf7_styler-col>p>span.uagb-cf7_styler-col-1{padding-right:15px;padding-left:0}.wp-block-uagb-cf7-styler .uagb-cf7_styler-col>p>span.uagb-cf7_styler-col-3{padding-right:0;padding-left:15px}.wp-block-uagb-cf7-styler .wpcf7 .uagb-cf7_styler-col span.wpcf7-form-control-wrap{height:100%}.wp-block-uagb-cf7-styler .wpcf7 .uagb-cf7_styler-col select{height:100%}}@media(min-width: 780px){.uagb-cf7-styler__btn-align-right input.wpcf7-form-control.wpcf7-submit{margin-right:0;margin-left:auto}.uagb-cf7-styler__btn-align-left input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:0}.uagb-cf7-styler__btn-align-center input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:auto}.uagb-cf7-styler__btn-align-justify input.wpcf7-form-control.wpcf7-submit{-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center;justify-content:center;width:100% !important}}@media(max-width: 780px){.uagb-cf7-styler__btn-align-tablet-right input.wpcf7-form-control.wpcf7-submit{margin-right:0;margin-left:auto}.uagb-cf7-styler__btn-align-tablet-left input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:0}.uagb-cf7-styler__btn-align-tablet-center input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:auto}}@media(min-width: 641px)and (max-width: 780px){.uagb-cf7-styler__btn-align-tablet-justify input.wpcf7-form-control.wpcf7-submit{-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center;justify-content:center;width:100% !important}}@media(max-width: 641px){.uagb-cf7-styler__btn-align-mobile-right input.wpcf7-form-control.wpcf7-submit{margin-right:0;margin-left:auto}.uagb-cf7-styler__btn-align-mobile-left input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:0}.uagb-cf7-styler__btn-align-mobile-center input.wpcf7-form-control.wpcf7-submit{margin-right:auto;margin-left:auto}.uagb-cf7-styler__btn-align-mobile-justify input.wpcf7-form-control.wpcf7-submit{-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center;justify-content:center;width:100% !important}}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c8e181d6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c8e181d6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-c8e181d6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2095f831 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2095f831{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2095f831 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2095f831{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-form{text-align: left;}.uagb-block-0bbd5a13 .wpcf7 form.wpcf7-form:not(input){color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 input:not([type=submit]){background-color: #283942;color: var(--ast-global-color-5);padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;text-align: left;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 select{background-color: #283942;color: var(--ast-global-color-5);text-align: left;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 select.wpcf7-form-control.wpcf7-select:not([multiple=\"multiple\"]){padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0bbd5a13 .wpcf7 select.wpcf7-select[multiple=\"multiple\"] option{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-0bbd5a13 .wpcf7 textarea{background-color: #283942;color: var(--ast-global-color-5);padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;text-align: left;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 textarea::placeholder{color: var(--ast-global-color-5);text-align: left;}.uagb-block-0bbd5a13 .wpcf7 input::placeholder{color: var(--ast-global-color-5);text-align: left;}.uagb-block-0bbd5a13 .wpcf7 form input:not([type=submit]):focus{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 form select:focus{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 textarea:focus{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit{color: var(--ast-global-color-5);background-color: var(--ast-global-color-0);padding-left: 25px;padding-right: 25px;padding-top: 10px;padding-bottom: 10px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit:hover{border-color: #333;}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit:focus{border-color: #333;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{background-color: #283942;color: var(--ast-global-color-5);font-size: calc( 10px \/ 1.2 );border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{background-color: #283942;color: var(--ast-global-color-5);height: 10px;width: 10px;font-size: calc( 10px \/ 1.2 );border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{background-color: #283942;color: var(--ast-global-color-5);font-size: calc( 10px \/ 1.2 );border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{background-color: #283942;color: var(--ast-global-color-5);height: 10px;width: 10px;font-size: calc( 10px \/ 1.2 );border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-radio input[type=\"radio\"] + span:before{background-color: #283942;color: var(--ast-global-color-5);height: 10px;width: 10px;border-style: solid;border-color: var(--ast-global-color-0);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-radio input[type=\"radio\"]:checked + span:before{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input:not([type=submit]){border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;border-bottom-width: 1px;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline textarea{border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;border-bottom-width: 1px;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline select{border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;border-bottom-width: 1px;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-checkbox input[type=\"checkbox\"] + span:before{border-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input[type=\"radio\"] + span:before{border-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-acceptance input[type=\"checkbox\"] + span:before{border-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{font-size: calc( 10px \/ 1.2 );border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{font-size: calc( 10px \/ 1.2 );border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: var(--ast-global-color-0);border-style: solid;}.uagb-block-0bbd5a13 .wpcf7-radio input[type=\"radio\"]:checked + span:before{background-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{background-color: var(--ast-global-color-5);color: var(--ast-global-color-0);font-size: calc( px \/ 1.2 );border-color: #abb8c3;}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{background-color: var(--ast-global-color-5);color: var(--ast-global-color-0);font-size: calc( px \/ 1.2 );border-color: #abb8c3;}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{border-color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 input[type=\"radio\"] + span:before{background-color: var(--ast-global-color-5);color: var(--ast-global-color-0);font-size: calc( px \/ 1.2 );border-color: #abb8c3;}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7-radio input[type=\"radio\"]:checked + span:before{background-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 span.wpcf7-not-valid-tip{color: #ff0000;}.uagb-block-0bbd5a13 .uagb-cf7-styler__highlight-border input.wpcf7-form-control.wpcf7-not-valid{border-color: #ff0000;}.uagb-block-0bbd5a13 .uagb-cf7-styler__highlight-border .wpcf7-form-control.wpcf7-not-valid .wpcf7-list-item-label:before{border-color: #ff0000!important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c8e181d6{width: 100%;}.wp-block-uagb-container.uagb-block-c8e181d6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2095f831{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2095f831 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2095f831{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-0bbd5a13 .wpcf7 input:not([type=submit]){border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 select{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 textarea{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 input[type=\"radio\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .wpcf7 form.wpcf7-form:not(input){color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit{border-style: solid;border-color: #333;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input:not([type=submit]){border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline select{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-checkbox input[type='checkbox'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input[type='radio'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-acceptance input[type='checkbox'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline textarea{border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-c8e181d6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-c8e181d6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2095f831{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2095f831 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2095f831{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-0bbd5a13 .wpcf7 input:not([type=submit]){border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 select{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-checkbox input[type=\"checkbox\"]:checked + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-box .wpcf7-acceptance input[type=\"checkbox\"]:checked + span:before{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .wpcf7 textarea{border-style: solid;border-color: var(--ast-global-color-0);}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-checkbox input[type=\"checkbox\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 .wpcf7-acceptance input[type=\"checkbox\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .uagb-cf7-styler__check-style-enabled .wpcf7 input[type=\"radio\"] + span:before{font-size: calc( px \/ 1.2 );}.uagb-block-0bbd5a13 .wpcf7 input.wpcf7-form-control.wpcf7-submit{border-style: solid;border-color: #333;}.uagb-block-0bbd5a13 .wpcf7 form.wpcf7-form:not(input){color: var(--ast-global-color-5);}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input:not([type=submit]){border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline select{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-checkbox input[type='checkbox'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7 input[type='radio'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline .wpcf7-acceptance input[type='checkbox'] + span:before{border-style: none;border-bottom-style: solid;}.uagb-block-0bbd5a13 .uagb-cf7-styler__field-style-underline textarea{border-style: none;border-bottom-color: var(--ast-global-color-0);border-bottom-style: solid;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-37fe9e23 .uagb-container__video-wrap video{opacity: 0.15;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-37fe9e23{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-37fe9e23{box-shadow: 0px 0px   #00000070 ;padding-top: 150px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/07\/altillo-estructura-metalica-02.jpg);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-37fe9e23::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-1);opacity: 0.85;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d36b578f .uagb-heading-text{font-size: 50px;}.wp-block-uagb-container.uagb-block-e4be775b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e4be775b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e4be775b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e4be775b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e4be775b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e4be775b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e4be775b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e4be775b{box-shadow: 0px 0px   #00000070 ;padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: #f5f5f5;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9a4bad7b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9a4bad7b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9a4bad7b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9a4bad7b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9a4bad7b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a4bad7b{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a4bad7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9a4bad7b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 100px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-639134ac .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-639134ac .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-5);}.uagb-block-639134ac .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-639134ac .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-icon-wrap svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-639134ac.uagb-infobox-icon-right .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-639134ac.uagb-infobox-icon-left .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-639134ac .uagb-infbox__link-to-all:hover ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-639134ac.uagb-infbox__link-to-all:hover ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-639134ac .uagb-infbox__link-to-all:focus ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-639134ac.uagb-infbox__link-to-all:focus ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-639134ac .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-639134ac .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-639134ac.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-639134ac .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-639134ac .uagb-ifb-title{margin-bottom: 7px;margin-left: 20px;}.uagb-block-639134ac .uagb-ifb-desc{margin-bottom: 0px;margin-left: 20px;}.uagb-block-639134ac .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-639134ac .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-639134ac .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-639134ac .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-639134ac .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-0);border-radius: 50%;}.uagb-block-639134ac .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-0);}.uagb-block-639134ac .uagb-iconbox-icon-wrap:hover{background-color: var(--ast-global-color-0) !important;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-image-content > img{width: 120px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 120px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 120px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 120px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-639134ac .uagb-iconbox-icon-wrap{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-639134ac.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-14f4c019 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-14f4c019 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-5);}.uagb-block-14f4c019 .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-14f4c019 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-icon-wrap svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-14f4c019.uagb-infobox-icon-right .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-14f4c019.uagb-infobox-icon-left .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-14f4c019 .uagb-infbox__link-to-all:hover ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-14f4c019.uagb-infbox__link-to-all:hover ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-14f4c019 .uagb-infbox__link-to-all:focus ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-14f4c019.uagb-infbox__link-to-all:focus ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-14f4c019 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14f4c019 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-14f4c019.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-14f4c019 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-14f4c019 .uagb-ifb-title{margin-bottom: 7px;margin-left: 20px;}.uagb-block-14f4c019 .uagb-ifb-desc{margin-bottom: 0px;margin-left: 20px;}.uagb-block-14f4c019 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-14f4c019 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-14f4c019 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-14f4c019 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-14f4c019 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-0);border-radius: 50%;}.uagb-block-14f4c019 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-0);}.uagb-block-14f4c019 .uagb-iconbox-icon-wrap:hover{background-color: var(--ast-global-color-0) !important;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-image-content > img{width: 120px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 120px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 120px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 120px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-14f4c019 .uagb-iconbox-icon-wrap{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-5807f0db .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5807f0db .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5807f0db .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5807f0db .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5807f0db .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5807f0db{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5807f0db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5807f0db{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 100px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-178fa41f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-178fa41f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-5);}.uagb-block-178fa41f .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-178fa41f .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-icon-wrap svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-178fa41f.uagb-infobox-icon-right .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-178fa41f.uagb-infobox-icon-left .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-178fa41f .uagb-infbox__link-to-all:hover ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-178fa41f.uagb-infbox__link-to-all:hover ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-178fa41f .uagb-infbox__link-to-all:focus ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-178fa41f.uagb-infbox__link-to-all:focus ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-178fa41f .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-178fa41f .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-178fa41f.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-178fa41f .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-178fa41f .uagb-ifb-title{margin-bottom: 7px;margin-left: 20px;}.uagb-block-178fa41f .uagb-ifb-desc{margin-bottom: 0px;margin-left: 20px;}.uagb-block-178fa41f .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-178fa41f .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-178fa41f .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-178fa41f .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-178fa41f .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-0);border-radius: 50%;}.uagb-block-178fa41f .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-0);}.uagb-block-178fa41f .uagb-iconbox-icon-wrap:hover{background-color: var(--ast-global-color-0) !important;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-image-content > img{width: 120px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 120px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 120px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 120px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-178fa41f .uagb-iconbox-icon-wrap{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e09bad92 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e09bad92 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: var(--ast-global-color-5);}.uagb-block-e09bad92 .uagb-ifb-icon svg{fill: var(--ast-global-color-5);}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-e09bad92 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: var(--ast-global-color-5);fill: var(--ast-global-color-5);}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-icon-wrap svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-e09bad92.uagb-infobox-icon-right .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-e09bad92.uagb-infobox-icon-left .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-3);color: var(--ast-global-color-3);}.uagb-block-e09bad92 .uagb-infbox__link-to-all:hover ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-e09bad92.uagb-infbox__link-to-all:hover ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-e09bad92 .uagb-infbox__link-to-all:focus ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-e09bad92.uagb-infbox__link-to-all:focus ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-3);}.uagb-block-e09bad92 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-e09bad92 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-e09bad92.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-e09bad92 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-e09bad92 .uagb-ifb-title{margin-bottom: 7px;margin-left: 20px;}.uagb-block-e09bad92 .uagb-ifb-desc{margin-bottom: 0px;margin-left: 20px;}.uagb-block-e09bad92 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-e09bad92 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-e09bad92 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e09bad92 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e09bad92 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-0);border-radius: 50%;}.uagb-block-e09bad92 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-0);}.uagb-block-e09bad92 .uagb-iconbox-icon-wrap:hover{background-color: var(--ast-global-color-0) !important;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-image-content > img{width: 120px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 120px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 120px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 120px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e09bad92 .uagb-iconbox-icon-wrap{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 10px;padding-left: 10px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01a5eb8e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5eb8e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5eb8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-01a5eb8e{box-shadow: 0px 0px   #00000070 ;padding-top: 80px;padding-bottom: -50px;padding-left: 0px;padding-right: 0px;margin-top: 50px !important;margin-bottom: 300px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a6b1f9db .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6b1f9db{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6b1f9db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a6b1f9db{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-0);flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3b8ab2e1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b8ab2e1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b8ab2e1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3b8ab2e1{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b0aef8d0.wp-block-uagb-container{color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-block-b0aef8d0.wp-block-uagb-container *{color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b0aef8d0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0aef8d0{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0aef8d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 30px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b0aef8d0{box-shadow: 0px 0px   #00000070 ;padding-top: 64px;padding-bottom: 64px;padding-left: 64px;padding-right: 64px;margin-top: -55px !important;margin-bottom: -250px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 30px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-37fe9e23{width: 100%;}.wp-block-uagb-container.uagb-block-37fe9e23{padding-top: 150px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/07\/altillo-estructura-metalica-02.jpg);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-37fe9e23::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-1);opacity: 0.85;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e4be775b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e4be775b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-e4be775b{padding-top: 60px;padding-bottom: 60px;padding-left: 200px;padding-right: 30px;margin-top: -40px !important;margin-bottom: -80px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f5f5f5;row-gap: 40px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a4bad7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a4bad7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9a4bad7b{padding-top: 10px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-639134ac .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-639134ac .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-639134ac .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-639134ac .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-639134ac.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 30%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-639134ac.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 30%;padding-bottom: 0%;padding-left: 0%;margin-top: 0px;margin-right: 0px;margin-bottom: 20px;margin-left: 0px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-image-content img{width: 120px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 120px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-left-title-image img{width: 120px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-right-title-image img{width: 120px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-14f4c019 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-14f4c019 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-14f4c019 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-14f4c019 .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-14f4c019.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 35%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-14f4c019.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 35%;padding-bottom: 0%;padding-left: 0%;margin-top: 0px;margin-right: 0px;margin-bottom: 20px;margin-left: 0px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-image-content img{width: 120px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 120px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 120px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 120px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5807f0db{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5807f0db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5807f0db{padding-top: 10px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-178fa41f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-178fa41f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-178fa41f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-178fa41f .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-178fa41f.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 30%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-178fa41f.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 30%;padding-bottom: 0%;padding-left: 0%;margin-top: 0px;margin-right: 0px;margin-bottom: 20px;margin-left: 0px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-image-content img{width: 120px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 120px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-left-title-image img{width: 120px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-right-title-image img{width: 120px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e09bad92 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e09bad92 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e09bad92 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e09bad92 .uagb-infobox-margin-wrapper{display: flex;}.uagb-block-e09bad92.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 35%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-e09bad92.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 35%;padding-bottom: 0%;padding-left: 0%;margin-top: 0px;margin-right: 0px;margin-bottom: 20px;margin-left: 0px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-image-content img{width: 120px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 120px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 120px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 120px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5eb8e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5eb8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-01a5eb8e{padding-top: 80px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 50px !important;margin-bottom: 300px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6b1f9db{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6b1f9db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a6b1f9db{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top: 0px !important;margin-bottom: -20px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-0);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b8ab2e1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b8ab2e1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3b8ab2e1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0aef8d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0aef8d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b0aef8d0{padding-top: 50px;padding-bottom: 50px;padding-left: 50px;padding-right: 50px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-37fe9e23{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-37fe9e23{padding-top: 100px;padding-bottom: 50px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/jansametal.com\/wp-content\/uploads\/2024\/07\/altillo-estructura-metalica-02.jpg);background-clip: padding-box;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-37fe9e23::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: var(--ast-global-color-1);opacity: 0.85;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e4be775b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e4be775b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 426px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-e4be775b{padding-top: 50px;padding-bottom: 50px;padding-left: 25px;padding-right: 25px;margin-top: -40px !important;margin-bottom: -80px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;background-color: #f5f5f5;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a4bad7b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a4bad7b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-9a4bad7b{padding-top: 10px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;flex-wrap: wrap;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-639134ac .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-639134ac .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-639134ac .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-639134ac .uagb-infobox-margin-wrapper{display: block;}.uagb-block-639134ac.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-639134ac.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-image-content img{width: 120px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 120px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-left-title-image img{width: 120px;}.uagb-block-639134ac .uagb-ifb-content .uagb-ifb-right-title-image img{width: 120px;}.uagb-block-639134ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-639134ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-14f4c019 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-14f4c019 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-14f4c019 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-14f4c019 .uagb-infobox-margin-wrapper{display: block;}.uagb-block-14f4c019.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-14f4c019.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-image-content img{width: 120px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 120px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 120px;}.uagb-block-14f4c019 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 120px;}.uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-14f4c019.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5807f0db{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5807f0db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-5807f0db{padding-top: 10px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;flex-wrap: wrap;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-178fa41f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-178fa41f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-178fa41f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-178fa41f .uagb-infobox-margin-wrapper{display: block;}.uagb-block-178fa41f.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-178fa41f.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-image-content img{width: 120px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 120px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-left-title-image img{width: 120px;}.uagb-block-178fa41f .uagb-ifb-content .uagb-ifb-right-title-image img{width: 120px;}.uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-178fa41f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e09bad92 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-e09bad92 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-e09bad92 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-e09bad92 .uagb-infobox-margin-wrapper{display: block;}.uagb-block-e09bad92.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-e09bad92.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-image-content img{width: 120px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 120px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 120px;}.uagb-block-e09bad92 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 120px;}.uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e09bad92.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01a5eb8e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01a5eb8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 426px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-01a5eb8e{padding-top: 80px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 80px !important;margin-bottom: 80px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a6b1f9db{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a6b1f9db > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a6b1f9db{padding-top: 100px;padding-bottom: 100px;padding-left: 25px;padding-right: 25px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-0);flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3b8ab2e1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3b8ab2e1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3b8ab2e1{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b0aef8d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b0aef8d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b0aef8d0{padding-top: 25px;padding-bottom: 25px;padding-left: 25px;padding-right: 25px;margin-top: -55px !important;margin-bottom: -55px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);flex-wrap: wrap;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.uagb-block-.wp-block-spectra-pro-login{width: 100%;box-shadow: 0px 0px   #00000070 ;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .wp-block-spectra-pro-login__logged-in-message{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login label{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login input{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__recaptcha{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass button span{font-size: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass label{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass input{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__forgetmenot{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a{font-style: normal;color: 1;margin: unset;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a:hover{color: 1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form-username-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form__user-pass .spectra-pro-login-form-pass-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-rememberme label{font-style: normal;margin: unset;}.uagb-block- .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark{width: 20px;height: 20px;border-width: 1px;border-radius: 2px;}.uagb-block- .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark:after{font-size: 10px;}.uagb-block- .spectra-pro-login-form-rememberme input[type=\"checkbox\"]:focus + .spectra-pro-login-form-rememberme__checkmark{box-shadow: 0 0 0 1px #2271b1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-register:hover{color: 1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__submit{justify-content: full;margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{font-style: normal;column-gap: 5px;width: 100%;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__success{border-left-color: #008000;background-color: #d4edda;color: #155724;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__error{border-left-color: #ff0000;background-color: #f8d7da;color: #721c24;}.uagb-block- .wp-block-spectra-pro-login-info{font-style: normal;}.uagb-block- .wp-block-spectra-pro-login-info a{color: 1;}.uagb-block- .wp-block-spectra-pro-login__logged-in-message a{color: 1;}.uagb-block- .wp-block-spectra-pro-login__logged-in-message a:hover{color: 1;}.wp-block-uagb-advanced-heading.uagb-block-e48442b8.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e48442b8.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e48442b8.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e48442b8.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.uagb-block-.wp-block-spectra-pro-login{width: 100%;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}@media only screen and (max-width: 767px) {.uagb-block-.wp-block-spectra-pro-login{width: 100%;padding-top: 20px;padding-right: 30px;padding-bottom: 20px;padding-left: 30px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login{width: 100%;box-shadow: 0px 0px   #00000070 ;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-login{margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .wp-block-spectra-pro-login__logged-in-message{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-login label{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-login input{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__recaptcha{margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass{margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass button span{font-size: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass label{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass input{font-style: normal;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__forgetmenot{margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a{font-style: normal;color: 1;margin: unset;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a:hover{color: 1;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form-username-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form__user-pass .spectra-pro-login-form-pass-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-rememberme label{font-style: normal;margin: unset;}.uagb-block-ff5fb2b1 .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark{width: 20px;height: 20px;border-width: 1px;border-radius: 2px;}.uagb-block-ff5fb2b1 .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark:after{font-size: 10px;}.uagb-block-ff5fb2b1 .spectra-pro-login-form-rememberme input[type=\"checkbox\"]:focus + .spectra-pro-login-form-rememberme__checkmark{box-shadow: 0 0 0 1px #2271b1;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-register:hover{color: 1;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form__submit{justify-content: full;margin-bottom: 20px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{font-style: normal;column-gap: 5px;width: 100%;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__success{border-left-color: #008000;background-color: #d4edda;color: #155724;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__error{border-left-color: #ff0000;background-color: #f8d7da;color: #721c24;}.uagb-block-ff5fb2b1 .wp-block-spectra-pro-login-info{font-style: normal;}.uagb-block-ff5fb2b1 .wp-block-spectra-pro-login-info a{color: 1;}.uagb-block-ff5fb2b1 .wp-block-spectra-pro-login__logged-in-message a{color: 1;}.uagb-block-ff5fb2b1 .wp-block-spectra-pro-login__logged-in-message a:hover{color: 1;}.wp-block-uagb-advanced-heading.uagb-block-971a0071.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-971a0071.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-971a0071.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-971a0071.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.uagb-block-ff5fb2b1.wp-block-spectra-pro-login{width: 100%;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}@media only screen and (max-width: 767px) {.uagb-block-ff5fb2b1.wp-block-spectra-pro-login{width: 100%;padding-top: 20px;padding-right: 30px;padding-bottom: 20px;padding-left: 30px;}.uagb-block-ff5fb2b1.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}.uagb-block-.wp-block-spectra-pro-login{width: 100%;box-shadow: 0px 0px   #00000070 ;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .wp-block-spectra-pro-login__logged-in-message{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login label{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-login input{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__recaptcha{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass button span{font-size: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass label{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__user-pass input{font-style: normal;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__forgetmenot{margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a{font-style: normal;color: 1;margin: unset;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-forgot-password a:hover{color: 1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form-username-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form .spectra-pro-login-form__user-pass .spectra-pro-login-form-pass-wrap--have-icon > svg{width: 12px;border-width: 1px;fill: #555D66;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-rememberme label{font-style: normal;margin: unset;}.uagb-block- .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark{width: 20px;height: 20px;border-width: 1px;border-radius: 2px;}.uagb-block- .spectra-pro-login-form-rememberme .spectra-pro-login-form-rememberme__checkmark:after{font-size: 10px;}.uagb-block- .spectra-pro-login-form-rememberme input[type=\"checkbox\"]:focus + .spectra-pro-login-form-rememberme__checkmark{box-shadow: 0 0 0 1px #2271b1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-register:hover{color: 1;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form__submit{justify-content: full;margin-bottom: 20px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{font-style: normal;column-gap: 5px;width: 100%;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__success{border-left-color: #008000;background-color: #d4edda;color: #155724;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-status .spectra-pro-login-form-status__error{border-left-color: #ff0000;background-color: #f8d7da;color: #721c24;}.uagb-block- .wp-block-spectra-pro-login-info{font-style: normal;}.uagb-block- .wp-block-spectra-pro-login-info a{color: 1;}.uagb-block- .wp-block-spectra-pro-login__logged-in-message a{color: 1;}.uagb-block- .wp-block-spectra-pro-login__logged-in-message a:hover{color: 1;}.wp-block-uagb-advanced-heading.uagb-block-634f5264.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-634f5264.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-634f5264.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-634f5264.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.uagb-block-.wp-block-spectra-pro-login{width: 100%;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}@media only screen and (max-width: 767px) {.uagb-block-.wp-block-spectra-pro-login{width: 100%;padding-top: 20px;padding-right: 30px;padding-bottom: 20px;padding-left: 30px;}.uagb-block-.wp-block-spectra-pro-login .spectra-pro-login-form-submit-button{width: 100%;}}\";s:2:\"js\";s:1669:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBLogin.init( '#spectra-pro-login-form-', '.uagb-block-', {\"ajax_url\":\"https:\/\/jansametal.com\/wp-admin\/admin-ajax.php\",\"post_id\":10579,\"block_id\":\"\",\"enableReCaptcha\":false,\"recaptchaVersion\":\"v2\",\"recaptchaSiteKey\":\"\",\"loginRedirectURL\":\"https:\/\/jansametal.com\/fr\/\",\"logoutRedirectURL\":\"https:\/\/jansametal.com\/fr\/\",\"this_field_error_msg\":{\"username\":\"Nombre de usuario o email ne peut pas u00eatre vide.\",\"password\":\"Contraseu00f1a ne peut pas u00eatre vide.\"}} );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBLogin.init( '#spectra-pro-login-form-ff5fb2b1', '.uagb-block-ff5fb2b1', {\"ajax_url\":\"https:\/\/jansametal.com\/wp-admin\/admin-ajax.php\",\"post_id\":10579,\"block_id\":\"ff5fb2b1\",\"enableReCaptcha\":false,\"recaptchaVersion\":\"v2\",\"recaptchaSiteKey\":\"\",\"loginRedirectURL\":\"https:\/\/jansametal.com\/fr\/\",\"logoutRedirectURL\":\"https:\/\/jansametal.com\/fr\/\",\"this_field_error_msg\":{\"username\":\"Nom d&#039;utilisateur ou adresse e-mail ne peut pas u00eatre vide.\",\"password\":\"Mot de passe ne peut pas u00eatre vide.\"}} );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBLogin.init( '#spectra-pro-login-form-', '.uagb-block-', {\"ajax_url\":\"https:\/\/jansametal.com\/wp-admin\/admin-ajax.php\",\"post_id\":10579,\"block_id\":\"\",\"enableReCaptcha\":false,\"recaptchaVersion\":\"v2\",\"recaptchaSiteKey\":\"\",\"loginRedirectURL\":\"https:\/\/jansametal.com\/fr\/\",\"logoutRedirectURL\":\"https:\/\/jansametal.com\/fr\/\",\"this_field_error_msg\":{\"username\":\"Nom d&#039;utilisateur ou adresse e-mail ne peut pas u00eatre vide.\",\"password\":\"Mot de passe ne peut pas u00eatre vide.\"}} );\n});\n });\";s:18:\"current_block_list\";a:14:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:4;s:13:\"uagb\/info-box\";i:8;s:12:\"core\/heading\";i:9;s:14:\"core\/paragraph\";i:13;s:15:\"uagb\/cf7-styler\";i:14;s:10:\"core\/group\";i:15;s:20:\"core\/latest-comments\";i:16;s:13:\"core\/archives\";i:17;s:10:\"uagb\/login\";i:18;s:10:\"core\/image\";i:19;s:11:\"core\/search\";i:20;s:17:\"core\/latest-posts\";i:21;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788340782\";s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wpca-thumb":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/jansametal.com\/fr\/author\/anjo\/"},"uagb_comment_info":0,"uagb_excerpt":"Ressources structures m\u00e9talliques Pr\u00eat pour la premi\u00e8re \u00e9tape ? Contactez-nous ! Tout grand projet commence par une conversation. Contactez-nous et d\u00e9couvrez comment nous pouvons concr\u00e9tiser votre id\u00e9e, avec des structures m\u00e9talliques aussi solides que vos attentes.","_links":{"self":[{"href":"https:\/\/jansametal.com\/fr\/wp-json\/wp\/v2\/pages\/10579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jansametal.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jansametal.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jansametal.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jansametal.com\/fr\/wp-json\/wp\/v2\/comments?post=10579"}],"version-history":[{"count":5,"href":"https:\/\/jansametal.com\/fr\/wp-json\/wp\/v2\/pages\/10579\/revisions"}],"predecessor-version":[{"id":14188,"href":"https:\/\/jansametal.com\/fr\/wp-json\/wp\/v2\/pages\/10579\/revisions\/14188"}],"wp:attachment":[{"href":"https:\/\/jansametal.com\/fr\/wp-json\/wp\/v2\/media?parent=10579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}